
{"id":6278,"count":1,"description":"","link":"https:\/\/blog.proclima.com\/de\/tag\/kooperation\/","name":"Kooperation","slug":"kooperation","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kooperation Archive &#187; pro clima Blog - Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.proclima.com\/de\/tag\/kooperation\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kooperation Archive &#187; pro clima Blog - Deutschland\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.proclima.com\/de\/tag\/kooperation\/\" \/>\n<meta property=\"og:site_name\" content=\"pro clima Blog - Deutschland\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@proclimaDE\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/tag\\\/kooperation\\\/\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/tag\\\/kooperation\\\/\",\"name\":\"Kooperation Archive &#187; pro clima Blog - Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/tag\\\/kooperation\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/tag\\\/kooperation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kooperation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\",\"name\":\"pro clima Blog - Deutschland\",\"description\":\"alles was pro clima bewegt\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#organization\",\"name\":\"pro clima - Moll bau\u00f6kologische Produkte GmbH\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2020\\\/04\\\/Logo-pro-clima.png\",\"contentUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2020\\\/04\\\/Logo-pro-clima.png\",\"width\":4210,\"height\":4881,\"caption\":\"pro clima - Moll bau\u00f6kologische Produkte GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/proclima\",\"https:\\\/\\\/x.com\\\/proclimaDE\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kooperation Archive &#187; pro clima Blog - Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.proclima.com\/de\/tag\/kooperation\/","og_locale":"de_DE","og_type":"article","og_title":"Kooperation Archive &#187; pro clima Blog - Deutschland","og_url":"https:\/\/blog.proclima.com\/de\/tag\/kooperation\/","og_site_name":"pro clima Blog - Deutschland","twitter_card":"summary_large_image","twitter_site":"@proclimaDE","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.proclima.com\/de\/tag\/kooperation\/","url":"https:\/\/blog.proclima.com\/de\/tag\/kooperation\/","name":"Kooperation Archive &#187; pro clima Blog - Deutschland","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/blog.proclima.com\/de\/tag\/kooperation\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.proclima.com\/de\/tag\/kooperation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.proclima.com\/de\/"},{"@type":"ListItem","position":2,"name":"Kooperation"}]},{"@type":"WebSite","@id":"https:\/\/blog.proclima.com\/de\/#website","url":"https:\/\/blog.proclima.com\/de\/","name":"pro clima Blog - Deutschland","description":"alles was pro clima bewegt","publisher":{"@id":"https:\/\/blog.proclima.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.proclima.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.proclima.com\/de\/#organization","name":"pro clima - Moll bau\u00f6kologische Produkte GmbH","url":"https:\/\/blog.proclima.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.proclima.com\/de\/files\/2020\/04\/Logo-pro-clima.png","contentUrl":"https:\/\/blog.proclima.com\/de\/files\/2020\/04\/Logo-pro-clima.png","width":4210,"height":4881,"caption":"pro clima - Moll bau\u00f6kologische Produkte GmbH"},"image":{"@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/proclima","https:\/\/x.com\/proclimaDE"]}]}},"_links":{"self":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/tags\/6278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts?tags=6278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}