{"id":5807,"date":"2016-06-06T13:21:24","date_gmt":"2016-06-06T11:21:24","guid":{"rendered":"http:\/\/blog.proclima.com\/de\/?p=5807"},"modified":"2017-10-10T20:06:32","modified_gmt":"2017-10-10T18:06:32","slug":"pm-bauslam-2016","status":"publish","type":"post","link":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/","title":{"rendered":"Mission erf\u00fcllt: \u00dcber 250 Menschen mit Bauwissen begeistert und vernetzt"},"content":{"rendered":"<p><i>Afterworkparty mit Slambeitr\u00e4gen: Der 2. Bauslam hat in Schwetzingen stattgefunden<\/i><\/p>\n<p><a href=\"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5808 size-large\" src=\"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4-1024x683.jpg\" alt=\"PM2016_09_Bauslam Nachbericht_4\" width=\"584\" height=\"390\" srcset=\"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4-1024x683.jpg 1024w, https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4-300x200.jpg 300w, https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4-768x512.jpg 768w, https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4-1536x1024.jpg 1536w, https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4-2048x1365.jpg 2048w, https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4-384x256.jpg 384w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/p>\n<p>Bauthemen mit Humor und einfach erkl\u00e4rt: Das war die Mission der sechs Slammer, die am 2. Juni 2016 in Schwetzingen vor mehr als 250 Menschen ihre Fachthemen pr\u00e4sentiert haben. Der Beifall des Publikums zeigte: Mission erf\u00fcllt.<br \/>\nDie Slam-Themen reichten von Missverst\u00e4ndnissen auf der Baustelle, \u00fcber Baurecht bis zu Schallschutz und Akustik. Nach der erfolgreichen Bauslam-Premiere 2015 waren die Besucher aus ganz Deutschland angereist, um den 2. Bauslam live zu erleben. Im Publikum sa\u00dfen Handwerker, Architekten, Energieberater, angehende Bauherren, Planer und Baustoffh\u00e4ndler.<!--more--><\/p>\n<figure id=\"attachment_5809\" aria-describedby=\"caption-attachment-5809\" style=\"width: 200px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_5_Jens-L\u00fcder-Herms5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5809 size-medium\" src=\"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_5_Jens-L\u00fcder-Herms5-200x300.jpg\" alt=\"PM2016_09_Bauslam Nachbericht_5_Jens-L\u00fcder Herms5\" width=\"200\" height=\"300\" srcset=\"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_5_Jens-L\u00fcder-Herms5-200x300.jpg 200w, https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_5_Jens-L\u00fcder-Herms5-683x1024.jpg 683w, https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_5_Jens-L\u00fcder-Herms5-768x1152.jpg 768w, https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_5_Jens-L\u00fcder-Herms5-1024x1536.jpg 1024w, https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_5_Jens-L\u00fcder-Herms5-1365x2048.jpg 1365w, https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_5_Jens-L\u00fcder-Herms5-256x384.jpg 256w, https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_5_Jens-L\u00fcder-Herms5-scaled.jpg 1707w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><figcaption id=\"caption-attachment-5809\" class=\"wp-caption-text\">Jens-L\u00fcder Herms aus der pro clima Forschung + Entwicklung pr\u00e4sentierte in 10 Minuten das Thema &#8222;Klebetechnik: die Wunderwelt der Klebstoffe&#8220;<\/figcaption><\/figure>\n<p><strong>Kommunikation unter den Bauleuten: Austausch zur Vermeidung von Fehlern auf der Baustelle<\/strong><\/p>\n<p>\u201eAuf der Baustelle passieren die meisten Fehler, weil sich die Gewerke teilweise nicht richtig abstimmen. Durch die Afterworkparty-Atmosph\u00e4re fand ein reger Austausch der Besucher statt \u2013 was hoffentlich dazu f\u00fchrt, dass die Vorurteile gegen\u00fcber verschiedenen Berufstypen abgebaut werden\u201c, sagte der Veranstalter des Bauslams Uwe Bartholom\u00e4i, Gesch\u00e4ftsf\u00fchrer von MOLL pro clima.<\/p>\n<p>Das Team Digital von pro clima, hat den Bauslam 2015 ins Leben gerufen: \u201eWie beim Poetry oder Science Slam wollen wir zeigen, dass Bauwissen nicht langatmig sein muss, sondern sogar richtig lustig sein kann\u201c, sagte Heide Gentner. Die Slammer pr\u00e4sentieren in jeweils zehn Minuten einen Bereich aus ihrer allt\u00e4glichen Arbeit: mit unterschiedlichen Vortragsmethoden und Requisiten. Auf <a href=\"http:\/\/www.bauslam.de\">www.bauslam.de<\/a> konnten Interessenten, die nicht in der Wollfabrik sein konnten, die Veranstaltung live mitverfolgen. In K\u00fcrze k\u00f6nnen die Slambeitr\u00e4ge auf den proclima.tv abgerufen werden. Teilnehmerfeedbacks und Nachberichte demn\u00e4chst auf <a href=\"http:\/\/www.bauslam.de\">www.bauslam.de<\/a>.<\/p>\n<figure id=\"attachment_5810\" aria-describedby=\"caption-attachment-5810\" style=\"width: 640px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_1.jpg\"><img loading=\"lazy\" decoding=\"async\" data-size=\"640x427\" class=\"wp-image-5810 size-full\" src=\"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_1.jpg\" alt=\"PM2016_09_Bauslam Nachbericht_1\" width=\"640\" height=\"427\" srcset=\"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_1.jpg 640w, https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_1-300x200.jpg 300w, https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_1-384x256.jpg 384w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><figcaption id=\"caption-attachment-5810\" class=\"wp-caption-text\">Die Bauslammer 2016 (von links nach rechts): Rechtsanwalt Andreas Weglage, Leo Morche (pro clima France), Uwe Bartholom\u00e4i (pro clima Gesch\u00e4ftsleitung), Jens-L\u00fcder Herms (pro clima Forschung + Entwicklung), Holger Merkel (Gesch\u00e4ftsf\u00fchrer bionic3 GmbH), Klaus G\u00fcnther (Bautraining Klaus G\u00fcnther).<\/figcaption><\/figure>\n<p>Weitere Infos:<\/p>\n<ul>\n<li><i>Eindr\u00fccke der Veranstaltung auf der Fotoplattform flickr:<br \/>\n<a href=\"https:\/\/www.flickr.com\/photos\/proclima\/sets\/72157668435365210\">https:\/\/www.flickr.com\/photos\/proclima\/sets\/72157668435365210<\/a><\/i><\/li>\n<li><i>Eindr\u00fccke &#8222;Bauslam &#8211; Hinter den Kulissen&#8220; auf der Fotoplattform flickr:<br \/>\n<a href=\"https:\/\/www.flickr.com\/photos\/proclima\/albums\/72157669277292825\">https:\/\/www.flickr.com\/photos\/proclima\/albums\/72157669277292825<\/a><\/i><\/li>\n<li><i>Diese Pressemitteilung als Doc und odt\u00a0 plus Fotos\u00a0 zum Download via Owncloud:<br \/>\n<a href=\"http:\/\/tinyurl.com\/gscu247\">http:\/\/tinyurl.com\/gscu247<\/a><\/i><\/li>\n<li><i>Fotos zur Pressemitteilung zum kostenlosen Download \u2013 ohne Anmeldung \u2013 auf der Bilddatenbank Picasso:\u00a0 <a href=\"http:\/\/tinyurl.com\/hbp6oqm\">http:\/\/tinyurl.com\/hbp6oqm<\/a><\/i><\/li>\n<li><i>Bauslam Blog: <a href=\"https:\/\/blog.proclima.com\/bauslam\/\">https:\/\/blog.proclima.com\/bauslam\/<\/a><\/i><\/li>\n<\/ul>\n<p>Diese Pressemitteilung als PDF:<br \/>\n<a href=\"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht.pdf\">PM2016_09_Bauslam Nachbericht<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Afterworkparty mit Slambeitr\u00e4gen: Der 2. Bauslam hat in Schwetzingen stattgefunden Bauthemen mit Humor und einfach erkl\u00e4rt: Das war die Mission der sechs Slammer, die am <a href=\"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/\" rel=\"bookmark\">&#8230;<\/a><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[136,3],"tags":[814,1101,816,863,1070,488,263,307,262,133,5],"class_list":["post-5807","post","type-post","status-publish","format-standard","hentry","category-pressemitteilung","category-veranstaltung","tag-andreas-weglage","tag-austausch","tag-baurecht","tag-bauslam","tag-bauslam-2016","tag-blowerdoor","tag-holger-merkel","tag-jens-luder-herms","tag-klaus-gunther","tag-leo-morche","tag-netzwerken"],"canto_acf_fields":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mission erf\u00fcllt: \u00dcber 250 Menschen mit Bauwissen begeistert und vernetzt - pro clima Blog - Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mission erf\u00fcllt: \u00dcber 250 Menschen mit Bauwissen begeistert und vernetzt - pro clima Blog - Deutschland\" \/>\n<meta property=\"og:description\" content=\"Afterworkparty mit Slambeitr\u00e4gen: Der 2. Bauslam hat in Schwetzingen stattgefunden Bauthemen mit Humor und einfach erkl\u00e4rt: Das war die Mission der sechs Slammer, die am ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"pro clima Blog - Deutschland\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-06T11:21:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-10T18:06:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4-1024x683.jpg\" \/>\n<meta name=\"author\" content=\"Julia Metzger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julia Metzger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/pm-bauslam-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/pm-bauslam-2016\\\/\"},\"author\":{\"name\":\"Julia Metzger\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/5592e4ea35eba419a493c8eecdff1062\"},\"headline\":\"Mission erf\u00fcllt: \u00dcber 250 Menschen mit Bauwissen begeistert und vernetzt\",\"datePublished\":\"2016-06-06T11:21:24+00:00\",\"dateModified\":\"2017-10-10T18:06:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/pm-bauslam-2016\\\/\"},\"wordCount\":423,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/pm-bauslam-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2016\\\/06\\\/PM2016_09_Bauslam-Nachbericht_4-1024x683.jpg\",\"keywords\":[\"Andreas Weglage\",\"Austausch\",\"Baurecht\",\"Bauslam\",\"Bauslam 2016\",\"BlowerDoor\",\"Holger Merkel\",\"Jens-L\u00fcder Herms\",\"Klaus G\u00fcnther\",\"Leo Morche\",\"Netzwerken\"],\"articleSection\":[\"Pressemitteilungen\",\"Veranstaltung\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/pm-bauslam-2016\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/pm-bauslam-2016\\\/\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/pm-bauslam-2016\\\/\",\"name\":\"Mission erf\u00fcllt: \u00dcber 250 Menschen mit Bauwissen begeistert und vernetzt - pro clima Blog - Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/pm-bauslam-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/pm-bauslam-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2016\\\/06\\\/PM2016_09_Bauslam-Nachbericht_4-1024x683.jpg\",\"datePublished\":\"2016-06-06T11:21:24+00:00\",\"dateModified\":\"2017-10-10T18:06:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/5592e4ea35eba419a493c8eecdff1062\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/pm-bauslam-2016\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/pm-bauslam-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/pm-bauslam-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2016\\\/06\\\/PM2016_09_Bauslam-Nachbericht_4-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2016\\\/06\\\/PM2016_09_Bauslam-Nachbericht_4-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/pm-bauslam-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mission erf\u00fcllt: \u00dcber 250 Menschen mit Bauwissen begeistert und vernetzt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\",\"name\":\"pro clima Blog - Deutschland\",\"description\":\"alles was pro clima bewegt\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/5592e4ea35eba419a493c8eecdff1062\",\"name\":\"Julia Metzger\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/author\\\/metzger\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mission erf\u00fcllt: \u00dcber 250 Menschen mit Bauwissen begeistert und vernetzt - pro clima Blog - Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/","og_locale":"de_DE","og_type":"article","og_title":"Mission erf\u00fcllt: \u00dcber 250 Menschen mit Bauwissen begeistert und vernetzt - pro clima Blog - Deutschland","og_description":"Afterworkparty mit Slambeitr\u00e4gen: Der 2. Bauslam hat in Schwetzingen stattgefunden Bauthemen mit Humor und einfach erkl\u00e4rt: Das war die Mission der sechs Slammer, die am ...","og_url":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/","og_site_name":"pro clima Blog - Deutschland","article_published_time":"2016-06-06T11:21:24+00:00","article_modified_time":"2017-10-10T18:06:32+00:00","og_image":[{"url":"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4-1024x683.jpg","type":"","width":"","height":""}],"author":"Julia Metzger","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Julia Metzger","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/#article","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/"},"author":{"name":"Julia Metzger","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/5592e4ea35eba419a493c8eecdff1062"},"headline":"Mission erf\u00fcllt: \u00dcber 250 Menschen mit Bauwissen begeistert und vernetzt","datePublished":"2016-06-06T11:21:24+00:00","dateModified":"2017-10-10T18:06:32+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/"},"wordCount":423,"commentCount":0,"image":{"@id":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4-1024x683.jpg","keywords":["Andreas Weglage","Austausch","Baurecht","Bauslam","Bauslam 2016","BlowerDoor","Holger Merkel","Jens-L\u00fcder Herms","Klaus G\u00fcnther","Leo Morche","Netzwerken"],"articleSection":["Pressemitteilungen","Veranstaltung"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/","url":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/","name":"Mission erf\u00fcllt: \u00dcber 250 Menschen mit Bauwissen begeistert und vernetzt - pro clima Blog - Deutschland","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/#primaryimage"},"image":{"@id":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4-1024x683.jpg","datePublished":"2016-06-06T11:21:24+00:00","dateModified":"2017-10-10T18:06:32+00:00","author":{"@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/5592e4ea35eba419a493c8eecdff1062"},"breadcrumb":{"@id":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/#primaryimage","url":"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4-scaled.jpg","contentUrl":"https:\/\/blog.proclima.com\/de\/files\/2016\/06\/PM2016_09_Bauslam-Nachbericht_4-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/blog.proclima.com\/de\/pm-bauslam-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/blog.proclima.com\/de\/"},{"@type":"ListItem","position":2,"name":"Mission erf\u00fcllt: \u00dcber 250 Menschen mit Bauwissen begeistert und vernetzt"}]},{"@type":"WebSite","@id":"https:\/\/blog.proclima.com\/de\/#website","url":"https:\/\/blog.proclima.com\/de\/","name":"pro clima Blog - Deutschland","description":"alles was pro clima bewegt","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.proclima.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/5592e4ea35eba419a493c8eecdff1062","name":"Julia Metzger","url":"https:\/\/blog.proclima.com\/de\/author\/metzger\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/5807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/comments?post=5807"}],"version-history":[{"count":17,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/5807\/revisions"}],"predecessor-version":[{"id":7213,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/5807\/revisions\/7213"}],"wp:attachment":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/media?parent=5807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/categories?post=5807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/tags?post=5807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}