
{"id":3982,"date":"2014-09-17T17:11:15","date_gmt":"2014-09-17T15:11:15","guid":{"rendered":"http:\/\/blog.proclima.com\/de\/?p=3982"},"modified":"2017-10-11T21:03:51","modified_gmt":"2017-10-11T19:03:51","slug":"dach-praxis-nachbericht","status":"publish","type":"post","link":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/","title":{"rendered":"[Pressemitteilung]: Kombischulung Dach-Praxis: Kritische Stellen bei Dachsanierungen erkennen und Fehler vermeiden"},"content":{"rendered":"<figure id=\"attachment_3983\" aria-describedby=\"caption-attachment-3983\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/1_Liveuebertragung.jpg\"><img loading=\"lazy\" decoding=\"async\" data-size=\"640x426\" class=\"size-full wp-image-3983\" src=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/1_Liveuebertragung.jpg\" alt=\"Alles Praxisteile des neuen Seminarkonzepts Dach-Praxis wurden live mitgefilmt und auf eine Leinwand \u00fcbertragen. So konnten alle Teilnehmer die schwierigen Schnittstellen vergr\u00f6\u00dfert sehen. Auf dem Foto: pro clima Schulungsleiter Thomas G\u00e4rtner\" width=\"640\" height=\"426\" srcset=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/1_Liveuebertragung.jpg 640w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/1_Liveuebertragung-300x200.jpg 300w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/1_Liveuebertragung-384x256.jpg 384w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><figcaption id=\"caption-attachment-3983\" class=\"wp-caption-text\">Alle Praxisteile des neuen Seminarkonzepts Dach-Praxis werden live mitgefilmt und auf eine Leinwand \u00fcbertragen. So k\u00f6nnen alle Teilnehmer die schwierigen Schnittstellen vergr\u00f6\u00dfert sehen. Auf dem Foto: pro clima Schulungsleiter Thomas G\u00e4rtner.<\/figcaption><\/figure>\n<p>In Deutschland werden immer mehr Sanierungen notwendig. Dabei stehen Zimmerer, Dachdecker und Planer h\u00e4ufig vor unerwarteten Herausforderungen, da Sanierungen einzigartig sind und bei jedem Objekt neue Situationen auftauchen. Das neue Seminarkonzept Dach-Praxis pr\u00e4sentierte daher 2013 L\u00f6sungen f\u00fcr knifflige Situationen und diskutierte mit den Teilnehmern individuelle Probleme. Aufgrund der hohen Nachfrage tourt das Dach-Praxis Team vom 15. Oktober bis 14. November 2014 quer durch Deutschland. Stationen sind: Rosenheim, Biberach, Butzbach, Kommern Eifel und Bremen.<\/p>\n<p>Im vergangenen Jahr besuchten 210 Handwerker, Berufsschullehrer, Architekten, Planer, H\u00e4ndler und Energieberater die Dach-Praxis Komibschulungen. \u201eIch habe diese Schulung ausgew\u00e4hlt, weil sie verschiedene Gewerke kombiniert und jedes Veranstaltungsmodul eine gute \u00dcbersicht zum aktuellen Stand der Technik gibt. Wir achten bei Planung und Verarbeitung besonders auf bauphysikalisch sensible Punkte. Daher ist es gut, hier den neusten Stand zu erfahren und dann auch im Praxisteil zu sehen\u201c, sagte Bauingenieur Matthias Reincke vom MR Holzbau aus Hamburg. Er war mit zwei Zimmerergesellen angereist.<\/p>\n<figure id=\"attachment_3985\" aria-describedby=\"caption-attachment-3985\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/2_Feedback_1.jpg\"><img loading=\"lazy\" decoding=\"async\" data-size=\"640x426\" class=\"size-full wp-image-3985\" src=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/2_Feedback_1.jpg\" alt=\"Teilnehmer Bauingenieur Matthias Reincke (links) mit Zimmerergesellen Dennis Br\u00f6han. Reincke sagte: \u201eIch habe diese Schulung ausgew\u00e4hlt, weil sie verschiedene Gewerke kombiniert und jedes Veranstaltungsmodul eine gute \u00dcbersicht zum aktuellen Stand der Technik gibt. \" width=\"640\" height=\"426\" srcset=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/2_Feedback_1.jpg 640w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/2_Feedback_1-300x200.jpg 300w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/2_Feedback_1-384x256.jpg 384w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><figcaption id=\"caption-attachment-3985\" class=\"wp-caption-text\">Teilnehmer Bauingenieur Matthias Reincke (links) mit Zimmerergesellen Dennis Br\u00f6han. Reincke sagte: \u201eIch habe diese Schulung ausgew\u00e4hlt, weil sie verschiedene Gewerke kombiniert und jedes Veranstaltungsmodul eine gute \u00dcbersicht zum aktuellen Stand der Technik gibt.<\/figcaption><\/figure>\n<p><!--more--><\/p>\n<p>Die Teilnehmer er\u00f6rterten untereinander und mit den Referenten anhand aktueller Projekte, wie sie komplizierte Details l\u00f6sen k\u00f6nnen und wie der Stand der Technik bei den verschiedenen Gewerken aussieht. Nico Sch\u00f6nfelder, Au\u00dfendienst von Roto, pr\u00e4sentierte live den kompletten Einbau eines Dachfl\u00e4chenfensters und wies auf potenzielle Fehlerstellen hin: \u201eAnschl\u00fcsse sind generell schwierig, weil es auf einer Baustelle immer anders aussieht als im Katalog. Die Winddichtung am<br \/>\nDachfenster ist bisher eine Grauzone, weil sie noch nicht verpflichtend ist. Aber wird sie nicht sichergestellt, kommt es oft zu Sch\u00e4den, weil Feuchtigkeit eindringt.\u201c<\/p>\n<p><strong>Live-\u00dcbertragung auf Leinwand<\/strong><br \/>\nAlle Praxisteile von Dach-Praxis werden gefilmt und live auf einer Leinwand gezeigt. So kann das Publikum die Details an den 1:1 Modellen deutlich und vergr\u00f6\u00dfert sehen.\u00a0 Das GUTEX-Referententeam zeigt im Praxisteil unter anderem verschiedene Varianten des Traufanschlusses: \u201eHier gibt es zwei einfache Tipps: Man kann die Unterdachbahn im ersten Horizontalsto\u00df der GUTEX Unterdeckplatte einschlaufen und bis zur Traufe vorziehen oder von der Traufvorderkante bis 30 cm unter die erste Reihe der Unterdeckplatten f\u00fchren. Die \u00dcberg\u00e4nge m\u00fcssen gut abgedichtet werden, weil sonst Wasser eindringen und es zu Sch\u00e4den an Konstruktionen kommen kann\u201c, erkl\u00e4rt Norbert Pauly von GUTEX.<\/p>\n<figure id=\"attachment_3986\" aria-describedby=\"caption-attachment-3986\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/3_GUTEX_Praxis.jpg\"><img loading=\"lazy\" decoding=\"async\" data-size=\"640x426\" class=\"size-full wp-image-3986\" src=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/3_GUTEX_Praxis.jpg\" alt=\"Referent Thorsten Siemens zeigte die kritischen Schnittstellen bei der Dachsanierung mit Holzfaserd\u00e4mmplatten.\" width=\"640\" height=\"426\" srcset=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/3_GUTEX_Praxis.jpg 640w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/3_GUTEX_Praxis-300x200.jpg 300w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/3_GUTEX_Praxis-384x256.jpg 384w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><figcaption id=\"caption-attachment-3986\" class=\"wp-caption-text\">Referent Thorsten Siemens zeigte die kritischen Schnittstellen bei der Dachsanierung mit Holzfaserd\u00e4mmplatten.<\/figcaption><\/figure>\n<p>Dachprofi Thomas G\u00e4rtner von pro clima erg\u00e4nzt: \u201eVielen ist nicht bewusst, dass man vor allem auf die Anschl\u00fcsse an der Traufe, am Ortgang und an den Durchdringungen achten muss. Das sollten alle Verarbeiter wissen, denn schlie\u00dflich m\u00fcssen sie auch dann daf\u00fcr haften, wenn sie es nicht wussten und sp\u00e4ter ein Bauschaden entsteht.\u201c<\/p>\n<figure id=\"attachment_3988\" aria-describedby=\"caption-attachment-3988\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/5_pc_Praxis.jpg\"><img loading=\"lazy\" decoding=\"async\" data-size=\"640x426\" class=\"size-full wp-image-3988\" src=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/5_pc_Praxis.jpg\" alt=\"pro clima Praxisschulungslseiter Thomas G\u00e4rtner zur korrekten Luftdichtung innen und Winddichtung au\u00dfen: \u201eVielen ist nicht bewusst, dass man vor allem auf die Anschl\u00fcsse an der Traufe, am Ortgang und an den Durchdringungen achten muss. Das sollten alle Verarbeiter wissen, denn schlie\u00dflich m\u00fcssen sie auch dann daf\u00fcr haften, wenn sie es nicht wussten und sp\u00e4ter ein Bauschaden entsteht.\u201c\" width=\"640\" height=\"426\" srcset=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/5_pc_Praxis.jpg 640w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/5_pc_Praxis-300x200.jpg 300w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/5_pc_Praxis-384x256.jpg 384w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><figcaption id=\"caption-attachment-3988\" class=\"wp-caption-text\">pro clima Praxisschulungslseiter Thomas G\u00e4rtner zur korrekten Luftdichtung innen und Winddichtung au\u00dfen: \u201eVielen ist nicht bewusst, dass man vor allem auf die Anschl\u00fcsse an der Traufe, am Ortgang und an den Durchdringungen achten muss. Das sollten alle Verarbeiter wissen, denn schlie\u00dflich m\u00fcssen sie auch dann daf\u00fcr haften, wenn sie es nicht wussten und sp\u00e4ter ein Bauschaden entsteht.\u201c<\/figcaption><\/figure>\n<p>Viele Teilnehmer interessieren sich f\u00fcr die verschiedenen M\u00f6glichkeiten, mit denen schnell und einfach komplizierte Details wie beispielsweise Kabeldurchdringungen abgedichtet werden k\u00f6nnen. Hier pr\u00e4sentiert pro clima Rohr- und Kabelmanschetten.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_3989\" aria-describedby=\"caption-attachment-3989\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/6_Feedback_2.jpg\"><img loading=\"lazy\" decoding=\"async\" data-size=\"320x480\" class=\"size-full wp-image-3989\" src=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/6_Feedback_2.jpg\" alt=\"Ingenieur Bernd Kinski aus Jevenstedt: \u201eIch arbeite seit f\u00fcnf Jahren als Energieberater und die Anfragen f\u00fcr Sanierungsbegleitungen steigen rasant. Das Seminar war eine gute Kombination, da sich die Veranstalter gewerke\u00fcbergreifend Gedanken gemacht haben und somit man die wichtigsten Schritte einer Dachsanierung sehen konnte: Von der Luftdichtungsebene, \u00fcber die D\u00e4mmung mit Holzfaserplatten bis zum korrekten Dachfl\u00e4chenfenstereinbau. Interessant fand ich einige Detaill\u00f6sungen f\u00fcr Anschl\u00fcsse an der Luftdichtungsebene und die Dachfenstermontage, sowie die L\u00f6sungen f\u00fcr die Luftdichtungsbahn oberhalb der Dachsparren. \u201c \" width=\"320\" height=\"480\" srcset=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/6_Feedback_2.jpg 320w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/6_Feedback_2-200x300.jpg 200w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/6_Feedback_2-256x384.jpg 256w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><figcaption id=\"caption-attachment-3989\" class=\"wp-caption-text\">Ingenieur Bernd Kinski aus Jevenstedt: \u201eIch arbeite seit f\u00fcnf Jahren als Energieberater und die Anfragen f\u00fcr Sanierungsbegleitungen steigen rasant. Das Seminar war eine gute Kombination, da sich die Veranstalter gewerke\u00fcbergreifend Gedanken gemacht haben und man somit die wichtigsten Schritte einer Dachsanierung sehen konnte: Von der Luftdichtungsebene, \u00fcber die D\u00e4mmung mit Holzfaserplatten, bis zum korrekten Dachfl\u00e4chenfenstereinbau. Interessant fand ich einige Detaill\u00f6sungen f\u00fcr Anschl\u00fcsse an der Luftdichtungsebene und die Dachfenstermontage, sowie die L\u00f6sungen f\u00fcr die Luftdichtungsbahn oberhalb der Dachsparren. \u201c<\/figcaption><\/figure>\n<p>Ingenieur Bernd Kinski aus Jevenstedt: \u201eIch arbeite seit f\u00fcnf Jahren als Energieberater und die Anfragen f\u00fcr Sanierungsbegleitungen steigen rasant. Das Seminar war eine gute Kombination, da sich die Veranstalter gewerke\u00fcbergreifend Gedanken gemacht haben und man somit die wichtigsten Schritte einer Dachsanierung sehen konnte: Von der Luftdichtungsebene, \u00fcber die D\u00e4mmung mit Holzfaserplatten bis zum korrekten Dachfl\u00e4chenfenstereinbau. Interessant fand ich einige Detaill\u00f6sungen f\u00fcr Anschl\u00fcsse an der Luftdichtungsebene und die Dachfenstermontage, sowie die L\u00f6sungen mit der Luftdichtungsbahn oberhalb der Dachsparren. \u201c<\/p>\n<figure id=\"attachment_3987\" aria-describedby=\"caption-attachment-3987\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/4_Roto_Praxis.jpg\"><img loading=\"lazy\" decoding=\"async\" data-size=\"320x480\" class=\"size-full wp-image-3987\" src=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/4_Roto_Praxis.jpg\" alt=\"Zimmerer Dirk Lamparter von Roto Dach und Solartechnologie demonstrierte, wie ein Dachfl\u00e4chenfenster fachgerecht eingebaut wird. \" width=\"320\" height=\"480\" srcset=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/4_Roto_Praxis.jpg 320w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/4_Roto_Praxis-200x300.jpg 200w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/4_Roto_Praxis-256x384.jpg 256w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><figcaption id=\"caption-attachment-3987\" class=\"wp-caption-text\">Zimmerer Dirk Lamparter von Roto Dach und Solartechnologie demonstrierte, wie ein Dachfl\u00e4chenfenster fachgerecht eingebaut wird.<\/figcaption><\/figure>\n<p>Dach-Praxis beleuchtet auch den Aspekt Wohngesundheit. So erkl\u00e4rte beispieslweise 2013 Referent Olaf Peter vom Sentinel Haus Institut, das wohngesunde Projekte ber\u00e4t, wie potenzielle Bauherren f\u00fcr das Wohngesunde Bauen sensibilisiert und begeistert werden k\u00f6nnen. Wer sich als Planer und Handwerker in Wohngesundheit auskennt, kann sich dadurch neue, qualit\u00e4tsbewusste Zielgruppen erschlie\u00dfen.<\/p>\n<p>Dass nachhaltiges Bauen die Zukunft pr\u00e4gen wird, best\u00e4tigte auch Gastredner Bundesminister a.D. Bj\u00f6rn Engholm 2013 in Hamburg. Er f\u00fchrte aus, dass diejenigen, die sich auf \u00f6kologisches, energieeffizientes Bauen und Sanieren spezialisieren k\u00fcnftig auch f\u00fchrend in der Branche sein werden.<\/p>\n<figure id=\"attachment_3991\" aria-describedby=\"caption-attachment-3991\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/7b_Engholm.jpg\"><img loading=\"lazy\" decoding=\"async\" data-size=\"640x426\" class=\"size-full wp-image-3991\" src=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/7b_Engholm.jpg\" alt=\"Bundesminister a.D. Bj\u00f6rn Engholm betonte, dass diejenigen, die sich auf \u00f6kologisches, energieeffizientes Bauen und Sanieren spezialisieren k\u00fcnftig auch f\u00fchrend in der Branche sein werden. \" width=\"640\" height=\"426\" srcset=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/7b_Engholm.jpg 640w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/7b_Engholm-300x200.jpg 300w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/7b_Engholm-384x256.jpg 384w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><figcaption id=\"caption-attachment-3991\" class=\"wp-caption-text\">Bundesminister a.D. Bj\u00f6rn Engholm betonte, dass diejenigen, die sich auf \u00f6kologisches, energieeffizientes Bauen und Sanieren spezialisieren k\u00fcnftig auch f\u00fchrend in der Branche sein werden.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>Fotos zur Pressemitteilung zum Download (Bildquelle: MOLL pro clima):<\/strong><br \/>\n<a href=\"https:\/\/picasso.moll-group.eu\/gallary\/main.php\/v\/pub\/dach-praxis-pm\/\" target=\"_blank\" rel=\"noopener\">https:\/\/picasso.moll-group.eu\/gallary\/main.php\/v\/pub\/dach-praxis-pm\/<\/a><\/p>\n<p>Alle Vortr\u00e4ge der Referenten k\u00f6nnen auf der Seite <a href=\"https:\/\/dachpraxis14.proclima.com\/\" target=\"_blank\" rel=\"noopener\">www.dach-praxis.de<\/a> kostenfrei heruntergeladen werden.<\/p>\n<p>Ein Video-Interview mit Bundesminister a.D. Bj\u00f6rn Engholm zum Thema nachhaltiges Bauen\u00a0 finden Sie hier: <a href=\"https:\/\/blog.proclima.com\/de\/2013\/10\/bjoern-engholm\/\" target=\"_blank\" rel=\"noopener\">https:\/\/blog.proclima.com\/de\/2013\/10\/bjoern-engholm\/<\/a><\/p>\n<p><strong>Weitere Artikel zur Kombischulung Dach-Praxis:<\/strong><\/p>\n<ul>\n<li><strong>So war die Kombischulung Dach-Praxis: \u201eLebendiges Publikum mit vielen kritischen Fragen\u201c \u2013 Feedback der Teilnehmer<\/strong><br \/>\n<a href=\"https:\/\/blog.proclima.com\/de\/2013\/10\/feedback-dach-praxis\/\" target=\"_blank\" rel=\"noopener\">https:\/\/blog.proclima.com\/de\/2013\/10\/feedback-dach-praxis\/<\/a><\/li>\n<li><strong>Dach-Praxis: \u201eJede Sanierung wirft neue Fragen auf \u2013 wir l\u00f6sen sie hier gemeinsam\u201c \u2013 n\u00e4chster Termin in Hamburg am 24.10.2013<\/strong><br \/>\n<a href=\"https:\/\/blog.proclima.com\/de\/2013\/10\/dach-praxis\/\" target=\"_blank\" rel=\"noopener\">https:\/\/blog.proclima.com\/de\/2013\/10\/dach-praxis\/<\/a><\/li>\n<li><strong>[Pressemitteilung]: Kompaktseminar zur sicheren Dachsanierung von au\u00dfen \u2013 Kombischulung Dach-Praxis mit GUTEX, pro clima und ROTO in Hamburg<\/strong><br \/>\n<a href=\"https:\/\/blog.proclima.com\/de\/2013\/10\/dachpraxis-seminar\/\" target=\"_blank\" rel=\"noopener\">https:\/\/blog.proclima.com\/de\/2013\/10\/dachpraxis-seminar\/<\/a><br \/>\n<strong><br \/>\nFotos zu Dach-Praxis zum kostenlosen Download (Bildquelle: MOLL pro clima)<\/strong><br \/>\n<a href=\"https:\/\/www.flickr.com\/photos\/proclima\/sets\/72157643952257965\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.flickr.com\/photos\/proclima\/sets\/72157643952257965\/<\/a><br \/>\n<a href=\"https:\/\/www.flickr.com\/photos\/proclima\/sets\/72157644007900475\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.flickr.com\/photos\/proclima\/sets\/72157644007900475\/<\/a><\/li>\n<\/ul>\n<p><strong>Pressekontakt<\/strong><br \/>\nHeide Gentner<br \/>\n<a href=\"mailto:heide.gentner@proclima.de\">heide.gentner@proclima.de<\/a><br \/>\nTel: 06202\/2782-56<\/p>\n<figure id=\"attachment_3992\" aria-describedby=\"caption-attachment-3992\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/8_Uebersicht.jpg\"><img loading=\"lazy\" decoding=\"async\" data-size=\"640x426\" class=\"size-full wp-image-3992\" src=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/8_Uebersicht.jpg\" alt=\"Das neue Konzept Dach-Praxis hat an drei Orten stattgefunden. Veranstalter waren pro clima, GUTEX und Roto Dach und Solartechnologie. Insgesamt haben 210 Verarbeiter, Planer und Energieberater teilgenommen.\" width=\"640\" height=\"426\" srcset=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/8_Uebersicht.jpg 640w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/8_Uebersicht-300x200.jpg 300w, https:\/\/blog.proclima.com\/de\/files\/2014\/09\/8_Uebersicht-384x256.jpg 384w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><figcaption id=\"caption-attachment-3992\" class=\"wp-caption-text\">Das neue Konzept Dach-Praxis hat an drei Orten stattgefunden. Veranstalter waren pro clima, GUTEX und Roto Dach und Solartechnologie. Insgesamt haben 210 Verarbeiter, Planer und Energieberater teilgenommen.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>In Deutschland werden immer mehr Sanierungen notwendig. Dabei stehen Zimmerer, Dachdecker und Planer h\u00e4ufig vor unerwarteten Herausforderungen, da Sanierungen einzigartig sind und bei jedem Objekt <a href=\"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/\" rel=\"bookmark\">&#8230;<\/a><\/p>\n","protected":false},"author":18,"featured_media":3992,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[136,6],"tags":[649,312,34,480,37,471,139],"class_list":["post-3982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pressemitteilung","category-schulungen","tag-dach-praxis","tag-dachsanierung","tag-pro-clima","tag-roto","tag-sanierung","tag-shi","tag-wohngesundheit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Pressemitteilung]: Kombischulung Dach-Praxis: Kritische Stellen bei Dachsanierungen erkennen und Fehler vermeiden &#187; pro clima Blog - Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Pressemitteilung]: Kombischulung Dach-Praxis: Kritische Stellen bei Dachsanierungen erkennen und Fehler vermeiden &#187; pro clima Blog - Deutschland\" \/>\n<meta property=\"og:description\" content=\"In Deutschland werden immer mehr Sanierungen notwendig. Dabei stehen Zimmerer, Dachdecker und Planer h\u00e4ufig vor unerwarteten Herausforderungen, da Sanierungen einzigartig sind und bei jedem Objekt ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/\" \/>\n<meta property=\"og:site_name\" content=\"pro clima Blog - Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proclima\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-17T15:11:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-11T19:03:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/8_Uebersicht.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Heide Merkel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@proclimaDE\" \/>\n<meta name=\"twitter:site\" content=\"@proclimaDE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Heide Merkel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2014\\\/09\\\/dach-praxis-nachbericht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2014\\\/09\\\/dach-praxis-nachbericht\\\/\"},\"author\":{\"name\":\"Heide Merkel\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/b3490e20200d5d45b8d56f555ceffc21\"},\"headline\":\"[Pressemitteilung]: Kombischulung Dach-Praxis: Kritische Stellen bei Dachsanierungen erkennen und Fehler vermeiden\",\"datePublished\":\"2014-09-17T15:11:15+00:00\",\"dateModified\":\"2017-10-11T19:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2014\\\/09\\\/dach-praxis-nachbericht\\\/\"},\"wordCount\":1167,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2014\\\/09\\\/dach-praxis-nachbericht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2014\\\/09\\\/8_Uebersicht.jpg\",\"keywords\":[\"Dach-Praxis\",\"Dachsanierung\",\"pro clima\",\"Roto\",\"Sanierung\",\"SHI\",\"Wohngesundheit\"],\"articleSection\":[\"Pressemitteilungen\",\"Schulungen\\\/Seminare\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2014\\\/09\\\/dach-praxis-nachbericht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2014\\\/09\\\/dach-praxis-nachbericht\\\/\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2014\\\/09\\\/dach-praxis-nachbericht\\\/\",\"name\":\"[Pressemitteilung]: Kombischulung Dach-Praxis: Kritische Stellen bei Dachsanierungen erkennen und Fehler vermeiden &#187; pro clima Blog - Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2014\\\/09\\\/dach-praxis-nachbericht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2014\\\/09\\\/dach-praxis-nachbericht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2014\\\/09\\\/8_Uebersicht.jpg\",\"datePublished\":\"2014-09-17T15:11:15+00:00\",\"dateModified\":\"2017-10-11T19:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2014\\\/09\\\/dach-praxis-nachbericht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2014\\\/09\\\/dach-praxis-nachbericht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2014\\\/09\\\/dach-praxis-nachbericht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2014\\\/09\\\/8_Uebersicht.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2014\\\/09\\\/8_Uebersicht.jpg\",\"width\":640,\"height\":426,\"caption\":\"Das neue Konzept Dach-Praxis hat an drei Orten stattgefunden. Veranstalter waren pro clima, GUTEX und Roto Dach und Solartechnologie. Insgesamt haben 210 Verarbeiter, Planer und Energieberater teilgenommen.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2014\\\/09\\\/dach-praxis-nachbericht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Pressemitteilung]: Kombischulung Dach-Praxis: Kritische Stellen bei Dachsanierungen erkennen und Fehler vermeiden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\",\"name\":\"pro clima Blog - Deutschland\",\"description\":\"alles was pro clima bewegt\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#organization\",\"name\":\"pro clima - Moll bau\u00f6kologische Produkte GmbH\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2020\\\/04\\\/Logo-pro-clima.png\",\"contentUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2020\\\/04\\\/Logo-pro-clima.png\",\"width\":4210,\"height\":4881,\"caption\":\"pro clima - Moll bau\u00f6kologische Produkte GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/proclima\",\"https:\\\/\\\/x.com\\\/proclimaDE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/b3490e20200d5d45b8d56f555ceffc21\",\"name\":\"Heide Merkel\",\"description\":\"Fachjournalistin, Referentin, Steuerung Presse &amp; Digitale Medien bei Moll bau\u00f6kologische Produkte GmbH (pro clima). Als Japanologin und ausgebildete Redakteurin ist Heide eher zuf\u00e4llig in der Baubranche gelandet. Seit 2011 arbeitet sie f\u00fcr pro clima. Ihr Wissen zu effektiver Kommunikation gibt sie in Seminaren, Artikeln und Vortr\u00e4gen weiter. F\u00fcr den pro clima Blog, proclima.tv und das pro clima Bauradio interviewt sie interessante Menschen aus der Baubranche. Auf\u00a0 luftdichtheit-gepr\u00fcft.de bloggt Heide \u00fcber Leckagen, Luftdichtung und Qualit\u00e4ts\u00fcberpr\u00fcfung mit Blower-Door-Tests. Ihre Freizeit verbringt sie u.a. in den Vogesen, wo sie seit mehr als f\u00fcnf Jahren ein altes Bauernhaus saniert. Ihr neuestes Projekt:\u00a0 www.besser-als-marketing.de Hier gibt es Tipps, wie Unternehmen in der Baubranche ihre Sichtbarkeit erh\u00f6hen k\u00f6nnen. Die ersten Videos sind bereits online im Youtube Channel Wer mehr \u00fcber Heide Merkel erfahren m\u00f6chte, findet sie auf den g\u00e4ngigen Social Media Plattformen.\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/author\\\/gentner\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Pressemitteilung]: Kombischulung Dach-Praxis: Kritische Stellen bei Dachsanierungen erkennen und Fehler vermeiden &#187; pro clima Blog - Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/","og_locale":"de_DE","og_type":"article","og_title":"[Pressemitteilung]: Kombischulung Dach-Praxis: Kritische Stellen bei Dachsanierungen erkennen und Fehler vermeiden &#187; pro clima Blog - Deutschland","og_description":"In Deutschland werden immer mehr Sanierungen notwendig. Dabei stehen Zimmerer, Dachdecker und Planer h\u00e4ufig vor unerwarteten Herausforderungen, da Sanierungen einzigartig sind und bei jedem Objekt ...","og_url":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/","og_site_name":"pro clima Blog - Deutschland","article_publisher":"https:\/\/www.facebook.com\/proclima","article_published_time":"2014-09-17T15:11:15+00:00","article_modified_time":"2017-10-11T19:03:51+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/8_Uebersicht.jpg","type":"image\/jpeg"}],"author":"Heide Merkel","twitter_card":"summary_large_image","twitter_creator":"@proclimaDE","twitter_site":"@proclimaDE","twitter_misc":{"Verfasst von":"Heide Merkel","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/#article","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/"},"author":{"name":"Heide Merkel","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/b3490e20200d5d45b8d56f555ceffc21"},"headline":"[Pressemitteilung]: Kombischulung Dach-Praxis: Kritische Stellen bei Dachsanierungen erkennen und Fehler vermeiden","datePublished":"2014-09-17T15:11:15+00:00","dateModified":"2017-10-11T19:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/"},"wordCount":1167,"commentCount":1,"publisher":{"@id":"https:\/\/blog.proclima.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/8_Uebersicht.jpg","keywords":["Dach-Praxis","Dachsanierung","pro clima","Roto","Sanierung","SHI","Wohngesundheit"],"articleSection":["Pressemitteilungen","Schulungen\/Seminare"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/","url":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/","name":"[Pressemitteilung]: Kombischulung Dach-Praxis: Kritische Stellen bei Dachsanierungen erkennen und Fehler vermeiden &#187; pro clima Blog - Deutschland","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/#primaryimage"},"image":{"@id":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/8_Uebersicht.jpg","datePublished":"2014-09-17T15:11:15+00:00","dateModified":"2017-10-11T19:03:51+00:00","breadcrumb":{"@id":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/#primaryimage","url":"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/8_Uebersicht.jpg","contentUrl":"https:\/\/blog.proclima.com\/de\/files\/2014\/09\/8_Uebersicht.jpg","width":640,"height":426,"caption":"Das neue Konzept Dach-Praxis hat an drei Orten stattgefunden. Veranstalter waren pro clima, GUTEX und Roto Dach und Solartechnologie. Insgesamt haben 210 Verarbeiter, Planer und Energieberater teilgenommen."},{"@type":"BreadcrumbList","@id":"https:\/\/blog.proclima.com\/de\/2014\/09\/dach-praxis-nachbericht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.proclima.com\/de\/"},{"@type":"ListItem","position":2,"name":"[Pressemitteilung]: Kombischulung Dach-Praxis: Kritische Stellen bei Dachsanierungen erkennen und Fehler vermeiden"}]},{"@type":"WebSite","@id":"https:\/\/blog.proclima.com\/de\/#website","url":"https:\/\/blog.proclima.com\/de\/","name":"pro clima Blog - Deutschland","description":"alles was pro clima bewegt","publisher":{"@id":"https:\/\/blog.proclima.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.proclima.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.proclima.com\/de\/#organization","name":"pro clima - Moll bau\u00f6kologische Produkte GmbH","url":"https:\/\/blog.proclima.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.proclima.com\/de\/files\/2020\/04\/Logo-pro-clima.png","contentUrl":"https:\/\/blog.proclima.com\/de\/files\/2020\/04\/Logo-pro-clima.png","width":4210,"height":4881,"caption":"pro clima - Moll bau\u00f6kologische Produkte GmbH"},"image":{"@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/proclima","https:\/\/x.com\/proclimaDE"]},{"@type":"Person","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/b3490e20200d5d45b8d56f555ceffc21","name":"Heide Merkel","description":"Fachjournalistin, Referentin, Steuerung Presse &amp; Digitale Medien bei Moll bau\u00f6kologische Produkte GmbH (pro clima). Als Japanologin und ausgebildete Redakteurin ist Heide eher zuf\u00e4llig in der Baubranche gelandet. Seit 2011 arbeitet sie f\u00fcr pro clima. Ihr Wissen zu effektiver Kommunikation gibt sie in Seminaren, Artikeln und Vortr\u00e4gen weiter. F\u00fcr den pro clima Blog, proclima.tv und das pro clima Bauradio interviewt sie interessante Menschen aus der Baubranche. Auf\u00a0 luftdichtheit-gepr\u00fcft.de bloggt Heide \u00fcber Leckagen, Luftdichtung und Qualit\u00e4ts\u00fcberpr\u00fcfung mit Blower-Door-Tests. Ihre Freizeit verbringt sie u.a. in den Vogesen, wo sie seit mehr als f\u00fcnf Jahren ein altes Bauernhaus saniert. Ihr neuestes Projekt:\u00a0 www.besser-als-marketing.de Hier gibt es Tipps, wie Unternehmen in der Baubranche ihre Sichtbarkeit erh\u00f6hen k\u00f6nnen. Die ersten Videos sind bereits online im Youtube Channel Wer mehr \u00fcber Heide Merkel erfahren m\u00f6chte, findet sie auf den g\u00e4ngigen Social Media Plattformen.","url":"https:\/\/blog.proclima.com\/de\/author\/gentner\/"}]}},"canto_acf_fields":"","_links":{"self":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/3982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/comments?post=3982"}],"version-history":[{"count":12,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/3982\/revisions"}],"predecessor-version":[{"id":7266,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/3982\/revisions\/7266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/media\/3992"}],"wp:attachment":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/media?parent=3982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/categories?post=3982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/tags?post=3982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}