{"id":3254,"date":"2013-09-19T06:00:46","date_gmt":"2013-09-19T04:00:46","guid":{"rendered":"http:\/\/blog.proclima.com\/de\/?p=3254"},"modified":"2013-09-18T17:41:46","modified_gmt":"2013-09-18T15:41:46","slug":"neubauten-shi-nordbau","status":"publish","type":"post","link":"https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/","title":{"rendered":"\u201eAuch Neubauten k\u00f6nnen krankmachen. Die Qualit\u00e4t der Innenraumflut ist in Deutschland gesetzlich nicht geregelt\u201c &#8211; Interview zu Wohngesundheit mit Architekten Olaf Peter vom SHI"},"content":{"rendered":"<div class=\"youtube-video left\"><iframe loading=\"lazy\" width=\"600\" height=\"340\" src=\"\/\/www.youtube.com\/embed\/?rel=0\" frameborder=\"0\" allowfullscreen><\/iframe><\/div>\n<p>Wohngesundheit \u2013 ist das nur ein Trend oder macht es Sinn, sich damit zu besch\u00e4ftigen? Heide Gentner hat mit dem Architekten Olaf Peter auf der Nordbau 2013 gesprochen. Peter vertrat dort das Sentinel Haus Institut, das wohngesunde Konzepte ber\u00e4t. Im Interview spricht Peter \u00fcber Neubauten, die krankmachen, \u00fcber nicht vorhandene Regelungen zur Innenraumluft und \u00fcber eine Datenbank, in der Bauherren, Planer und Verarbeiter wohngesunde Baustoffe finden.<\/p>\n<p>\u00dcbersicht der Fragen <!--more--><\/p>\n<ul>\n<li>Die Organisatoren der Nordbau 2013 haben das Sentinel Haus Institut gebeten, den Infopoint sicher wohnen \u2013 sicher bauen zu gestalten. Warum ist das so ein wichtiges Thema?<\/li>\n<li>Wer interessiert sich f\u00fcr wohngesundes Bauen? Allergiker, Verarbeiter, Bauherren?<\/li>\n<li>Ist die Nachfrage nach Wohngesundheit gestiegen? Woran liegt das?<\/li>\n<li>Neue Geb\u00e4ude sollen krankmachen? Das h\u00f6rt sich paradox an. Wie oft kommt das vor und\u00a0 wie kann das sein?<\/li>\n<li>Gibt es eine Tendenz, dass k\u00fcnftig die Innenraumluft in Deutschland auch gesetzlich geregelt wird?<\/li>\n<li>Wie kann ich als Bauherr sichergehen, dass mein Projekt wohngesund wird? Wer kennt sich damit aus?<\/li>\n<li>Pr\u00fcft das SHI auch Konstruktionen auf Wohngesundheit und vergibt Zertifikate?<\/li>\n<li>Kann ich auch nachtr\u00e4glich pr\u00fcfen lassen, ob mein Haus bzw. meine Wohnung eine gute Raumluft hat?<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wohngesundheit \u2013 ist das nur ein Trend oder macht es Sinn, sich damit zu besch\u00e4ftigen? Heide Gentner hat mit dem Architekten Olaf Peter auf der <a href=\"https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/\" rel=\"bookmark\">&#8230;<\/a><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[612,486,471],"class_list":["post-3254","post","type-post","status-publish","format-standard","hentry","category-proclima","tag-nordbau","tag-olaf-peter","tag-shi"],"canto_acf_fields":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201eAuch Neubauten k\u00f6nnen krankmachen. Die Qualit\u00e4t der Innenraumflut ist in Deutschland gesetzlich nicht geregelt\u201c - Interview zu Wohngesundheit mit Architekten Olaf Peter vom SHI  - pro clima Blog - Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201eAuch Neubauten k\u00f6nnen krankmachen. Die Qualit\u00e4t der Innenraumflut ist in Deutschland gesetzlich nicht geregelt\u201c - Interview zu Wohngesundheit mit Architekten Olaf Peter vom SHI  - pro clima Blog - Deutschland\" \/>\n<meta property=\"og:description\" content=\"Wohngesundheit \u2013 ist das nur ein Trend oder macht es Sinn, sich damit zu besch\u00e4ftigen? Heide Gentner hat mit dem Architekten Olaf Peter auf der ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/\" \/>\n<meta property=\"og:site_name\" content=\"pro clima Blog - Deutschland\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-19T04:00:46+00:00\" \/>\n<meta name=\"author\" content=\"Heide Merkel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Heide Merkel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/neubauten-shi-nordbau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/neubauten-shi-nordbau\\\/\"},\"author\":{\"name\":\"Heide Merkel\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/d82bffdd044ae90e51f35347afa56918\"},\"headline\":\"\u201eAuch Neubauten k\u00f6nnen krankmachen. Die Qualit\u00e4t der Innenraumflut ist in Deutschland gesetzlich nicht geregelt\u201c &#8211; Interview zu Wohngesundheit mit Architekten Olaf Peter vom SHI\",\"datePublished\":\"2013-09-19T04:00:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/neubauten-shi-nordbau\\\/\"},\"wordCount\":224,\"commentCount\":0,\"keywords\":[\"Nordbau\",\"Olaf Peter\",\"SHI\"],\"articleSection\":[\"pro clima\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/neubauten-shi-nordbau\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/neubauten-shi-nordbau\\\/\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/neubauten-shi-nordbau\\\/\",\"name\":\"\u201eAuch Neubauten k\u00f6nnen krankmachen. Die Qualit\u00e4t der Innenraumflut ist in Deutschland gesetzlich nicht geregelt\u201c - Interview zu Wohngesundheit mit Architekten Olaf Peter vom SHI - pro clima Blog - Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\"},\"datePublished\":\"2013-09-19T04:00:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/d82bffdd044ae90e51f35347afa56918\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/neubauten-shi-nordbau\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/neubauten-shi-nordbau\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/neubauten-shi-nordbau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201eAuch Neubauten k\u00f6nnen krankmachen. Die Qualit\u00e4t der Innenraumflut ist in Deutschland gesetzlich nicht geregelt\u201c &#8211; Interview zu Wohngesundheit mit Architekten Olaf Peter vom SHI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\",\"name\":\"pro clima Blog - Deutschland\",\"description\":\"alles was pro clima bewegt\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/d82bffdd044ae90e51f35347afa56918\",\"name\":\"Heide Merkel\",\"description\":\"Fachjournalistin, Referentin, Steuerung Presse &amp; Digitale Medien bei Moll bau\u00f6kologische Produkte GmbH (pro clima). Als Japanologin und ausgebildete Redakteurin ist Heide eher zuf\u00e4llig in der Baubranche gelandet. Seit 2011 arbeitet sie f\u00fcr pro clima. Ihr Wissen zu effektiver Kommunikation gibt sie in Seminaren, Artikeln und Vortr\u00e4gen weiter. F\u00fcr den pro clima Blog, proclima.tv und das pro clima Bauradio interviewt sie interessante Menschen aus der Baubranche. Auf\u00a0 luftdichtheit-gepr\u00fcft.de bloggt Heide \u00fcber Leckagen, Luftdichtung und Qualit\u00e4ts\u00fcberpr\u00fcfung mit Blower-Door-Tests. Ihre Freizeit verbringt sie u.a. in den Vogesen, wo sie seit mehr als f\u00fcnf Jahren ein altes Bauernhaus saniert. Ihr neuestes Projekt:\u00a0 www.besser-als-marketing.de Hier gibt es Tipps, wie Unternehmen in der Baubranche ihre Sichtbarkeit erh\u00f6hen k\u00f6nnen. Die ersten Videos sind bereits online im Youtube Channel Wer mehr \u00fcber Heide Merkel erfahren m\u00f6chte, findet sie auf den g\u00e4ngigen Social Media Plattformen.\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/author\\\/gentner\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201eAuch Neubauten k\u00f6nnen krankmachen. Die Qualit\u00e4t der Innenraumflut ist in Deutschland gesetzlich nicht geregelt\u201c - Interview zu Wohngesundheit mit Architekten Olaf Peter vom SHI  - pro clima Blog - Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/","og_locale":"de_DE","og_type":"article","og_title":"\u201eAuch Neubauten k\u00f6nnen krankmachen. Die Qualit\u00e4t der Innenraumflut ist in Deutschland gesetzlich nicht geregelt\u201c - Interview zu Wohngesundheit mit Architekten Olaf Peter vom SHI  - pro clima Blog - Deutschland","og_description":"Wohngesundheit \u2013 ist das nur ein Trend oder macht es Sinn, sich damit zu besch\u00e4ftigen? Heide Gentner hat mit dem Architekten Olaf Peter auf der ...","og_url":"https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/","og_site_name":"pro clima Blog - Deutschland","article_published_time":"2013-09-19T04:00:46+00:00","author":"Heide Merkel","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Heide Merkel","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/#article","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/"},"author":{"name":"Heide Merkel","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/d82bffdd044ae90e51f35347afa56918"},"headline":"\u201eAuch Neubauten k\u00f6nnen krankmachen. Die Qualit\u00e4t der Innenraumflut ist in Deutschland gesetzlich nicht geregelt\u201c &#8211; Interview zu Wohngesundheit mit Architekten Olaf Peter vom SHI","datePublished":"2013-09-19T04:00:46+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/"},"wordCount":224,"commentCount":0,"keywords":["Nordbau","Olaf Peter","SHI"],"articleSection":["pro clima"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/","url":"https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/","name":"\u201eAuch Neubauten k\u00f6nnen krankmachen. Die Qualit\u00e4t der Innenraumflut ist in Deutschland gesetzlich nicht geregelt\u201c - Interview zu Wohngesundheit mit Architekten Olaf Peter vom SHI - pro clima Blog - Deutschland","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/#website"},"datePublished":"2013-09-19T04:00:46+00:00","author":{"@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/d82bffdd044ae90e51f35347afa56918"},"breadcrumb":{"@id":"https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.proclima.com\/de\/neubauten-shi-nordbau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/blog.proclima.com\/de\/"},{"@type":"ListItem","position":2,"name":"\u201eAuch Neubauten k\u00f6nnen krankmachen. Die Qualit\u00e4t der Innenraumflut ist in Deutschland gesetzlich nicht geregelt\u201c &#8211; Interview zu Wohngesundheit mit Architekten Olaf Peter vom SHI"}]},{"@type":"WebSite","@id":"https:\/\/blog.proclima.com\/de\/#website","url":"https:\/\/blog.proclima.com\/de\/","name":"pro clima Blog - Deutschland","description":"alles was pro clima bewegt","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.proclima.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/d82bffdd044ae90e51f35347afa56918","name":"Heide Merkel","description":"Fachjournalistin, Referentin, Steuerung Presse &amp; Digitale Medien bei Moll bau\u00f6kologische Produkte GmbH (pro clima). Als Japanologin und ausgebildete Redakteurin ist Heide eher zuf\u00e4llig in der Baubranche gelandet. Seit 2011 arbeitet sie f\u00fcr pro clima. Ihr Wissen zu effektiver Kommunikation gibt sie in Seminaren, Artikeln und Vortr\u00e4gen weiter. F\u00fcr den pro clima Blog, proclima.tv und das pro clima Bauradio interviewt sie interessante Menschen aus der Baubranche. Auf\u00a0 luftdichtheit-gepr\u00fcft.de bloggt Heide \u00fcber Leckagen, Luftdichtung und Qualit\u00e4ts\u00fcberpr\u00fcfung mit Blower-Door-Tests. Ihre Freizeit verbringt sie u.a. in den Vogesen, wo sie seit mehr als f\u00fcnf Jahren ein altes Bauernhaus saniert. Ihr neuestes Projekt:\u00a0 www.besser-als-marketing.de Hier gibt es Tipps, wie Unternehmen in der Baubranche ihre Sichtbarkeit erh\u00f6hen k\u00f6nnen. Die ersten Videos sind bereits online im Youtube Channel Wer mehr \u00fcber Heide Merkel erfahren m\u00f6chte, findet sie auf den g\u00e4ngigen Social Media Plattformen.","url":"https:\/\/blog.proclima.com\/de\/author\/gentner\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/3254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/comments?post=3254"}],"version-history":[{"count":1,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/3254\/revisions"}],"predecessor-version":[{"id":3255,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/3254\/revisions\/3255"}],"wp:attachment":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/media?parent=3254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/categories?post=3254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/tags?post=3254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}