{"id":3062,"date":"2013-06-10T10:47:48","date_gmt":"2013-06-10T08:47:48","guid":{"rendered":"http:\/\/blog.proclima.com\/de\/?p=3062"},"modified":"2013-06-11T11:32:11","modified_gmt":"2013-06-11T09:32:11","slug":"buildair","status":"publish","type":"post","link":"https:\/\/blog.proclima.com\/de\/buildair\/","title":{"rendered":"BUILDAIR 2013 &#8211; Eindr\u00fccke der pro clima Regionalvertretung Nord"},"content":{"rendered":"<figure id=\"attachment_3065\" aria-describedby=\"caption-attachment-3065\" style=\"width: 409px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2013\/06\/IMG_1457.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3065 \" alt=\"Von links: pro clima Gr\u00fcnder Lothar Moll, Ruwen, Detlef und Joachim Gro\u00df von gross-baupraxis.de (pro clima Regionalvertretung Nord), Energieberater Frank Brockmann und pro clima Techniker Stefan H\u00fcckst\u00e4dt\" src=\"https:\/\/blog.proclima.com\/de\/files\/2013\/06\/IMG_1457-1024x682.jpg\" width=\"409\" height=\"272\" \/><\/a><figcaption id=\"caption-attachment-3065\" class=\"wp-caption-text\">Von links: pro clima Gr\u00fcnder Lothar Moll, Ruwen, Detlef und Joachim Gro\u00df von gross-baupraxis.de (pro clima Regionalvertretung Nord), Energieberater Frank Brockmann und pro clima Techniker Stefan H\u00fcckst\u00e4dt auf der BUILDAIR 2013 in Hannover.<\/figcaption><\/figure>\n<p>Neben dem pro clima Gr\u00fcnder Lothar Moll und Ingenieur Stefan H\u00fcckst\u00e4dt, ist auch die pro clima Regionalvertretung Nord auf der BUILDAIR 2013 in Hannover gewesen. Das Team um <a href=\"http:\/\/www.gross-baupraxis.de\/\" target=\"_blank\">Joachim Gro\u00df von baupraxis<\/a> hat zwei Tage lang den pro clima Stand in Hannover betreut und beschreibt seine Eindr\u00fccke: <!--more--><\/p>\n<figure id=\"attachment_3064\" aria-describedby=\"caption-attachment-3064\" style=\"width: 350px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2013\/06\/IMG_1443.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3064 \" alt=\"pro clima Stand auf der BUILDAIR\" src=\"https:\/\/blog.proclima.com\/de\/files\/2013\/06\/IMG_1443-1024x682.jpg\" width=\"350\" height=\"233\" \/><\/a><figcaption id=\"caption-attachment-3064\" class=\"wp-caption-text\">pro clima Stand auf der BUILDAIR<\/figcaption><\/figure>\n<p>&#8222;Seit mehr als zehn Jahren betreue ich als pro clima Regionalvertretung Nord das BUILDAIR Symposium\u201c, erz\u00e4hlt Joachim Gro\u00df, \u201edas Thema Luftdichtheit in der Geb\u00e4udeh\u00fclle hat sich in den vergangenen 20 Jahren enorm entwickelt. Es gibt viele langj\u00e4hrige Weggef\u00e4hrten und ich bin jedes Jahr gespannt, wen ich hier erneut treffen darf. Es handelt sich dabei um ein besonderes Klassentreffen.&#8220;<\/p>\n<p>&#8222;In dem quasi Jubil\u00e4umsjahr der internationalen BUILDAIR hat sich pro clima mit dem bislang gr\u00f6\u00dften Team pr\u00e4sentiert und sich den Fachfragen der interessierten Besucher gestellt. Wir haben mit Spa\u00df und Know-how beraten&#8220;, fasst Joachim Gro\u00df zusammen.<\/p>\n<p>Weitere Artikel:<\/p>\n<ul>\n<li><a href=\"https:\/\/blog.proclima.com\/de\/2013\/06\/hannover-symposium\/\" target=\"_blank\"><strong>8. Internationales BUILDAIR Symposium 2013 in Hannover<\/strong><\/a><br \/>\n<a href=\"https:\/\/blog.proclima.com\/de\/2013\/06\/hannover-symposium\/\" target=\"_blank\">https:\/\/blog.proclima.com\/de\/2013\/06\/hannover-symposium\/<\/a><\/li>\n<li><strong><a href=\"https:\/\/blog.proclima.com\/de\/2012\/05\/buildair-2012-ruckblick\/\" target=\"_blank\">BUILDAIR 2012 : \u201ePlanung der Luftdichtungsebene in Zukunft anspruchsvoller\u201c<\/a><\/strong><br \/>\n<a href=\"https:\/\/blog.proclima.com\/de\/2012\/05\/buildair-2012-ruckblick\/\" target=\"_blank\">https:\/\/blog.proclima.com\/de\/2012\/05\/buildair-2012-ruckblick\/<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neben dem pro clima Gr\u00fcnder Lothar Moll und Ingenieur Stefan H\u00fcckst\u00e4dt, ist auch die pro clima Regionalvertretung Nord auf der BUILDAIR 2013 in Hannover gewesen. <a href=\"https:\/\/blog.proclima.com\/de\/buildair\/\" rel=\"bookmark\">&#8230;<\/a><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[569,259,144,566,542],"class_list":["post-3062","post","type-post","status-publish","format-standard","hentry","category-proclima","tag-detlef-gros","tag-joachim-gros","tag-lothar-moll","tag-pro-clima-grunder","tag-stefan-huckstadt"],"canto_acf_fields":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BUILDAIR 2013 - Eindr\u00fccke der pro clima Regionalvertretung Nord  - pro clima Blog - Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.proclima.com\/de\/buildair\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BUILDAIR 2013 - Eindr\u00fccke der pro clima Regionalvertretung Nord  - pro clima Blog - Deutschland\" \/>\n<meta property=\"og:description\" content=\"Neben dem pro clima Gr\u00fcnder Lothar Moll und Ingenieur Stefan H\u00fcckst\u00e4dt, ist auch die pro clima Regionalvertretung Nord auf der BUILDAIR 2013 in Hannover gewesen. ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.proclima.com\/de\/buildair\/\" \/>\n<meta property=\"og:site_name\" content=\"pro clima Blog - Deutschland\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-10T08:47:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-06-11T09:32:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.proclima.com\/de\/files\/2013\/06\/IMG_1457-1024x682.jpg\" \/>\n<meta name=\"author\" content=\"Heide Merkel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Heide Merkel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/buildair\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/buildair\\\/\"},\"author\":{\"name\":\"Heide Merkel\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/d82bffdd044ae90e51f35347afa56918\"},\"headline\":\"BUILDAIR 2013 &#8211; Eindr\u00fccke der pro clima Regionalvertretung Nord\",\"datePublished\":\"2013-06-10T08:47:48+00:00\",\"dateModified\":\"2013-06-11T09:32:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/buildair\\\/\"},\"wordCount\":244,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/buildair\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2013\\\/06\\\/IMG_1457-1024x682.jpg\",\"keywords\":[\"Detlef Gro\u00df\",\"Joachim Gro\u00df\",\"Lothar Moll\",\"pro clima Gr\u00fcnder\",\"Stefan H\u00fcckst\u00e4dt\"],\"articleSection\":[\"pro clima\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/buildair\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/buildair\\\/\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/buildair\\\/\",\"name\":\"BUILDAIR 2013 - Eindr\u00fccke der pro clima Regionalvertretung Nord - pro clima Blog - Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/buildair\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/buildair\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2013\\\/06\\\/IMG_1457-1024x682.jpg\",\"datePublished\":\"2013-06-10T08:47:48+00:00\",\"dateModified\":\"2013-06-11T09:32:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/d82bffdd044ae90e51f35347afa56918\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/buildair\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/buildair\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/buildair\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2013\\\/06\\\/IMG_1457-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2013\\\/06\\\/IMG_1457-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Von links: pro clima Gr\u00fcnder Lothar Moll, Ruwen, Detlef und Joachim Gro\u00df von gross-baupraxis.de (pro clima Regionalvertretung Nord), Energieberater Frank Brockmann und pro clima Techniker Stefan H\u00fcckst\u00e4dt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/buildair\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BUILDAIR 2013 &#8211; Eindr\u00fccke der pro clima Regionalvertretung Nord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\",\"name\":\"pro clima Blog - Deutschland\",\"description\":\"alles was pro clima bewegt\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/d82bffdd044ae90e51f35347afa56918\",\"name\":\"Heide Merkel\",\"description\":\"Fachjournalistin, Referentin, Steuerung Presse &amp; Digitale Medien bei Moll bau\u00f6kologische Produkte GmbH (pro clima). Als Japanologin und ausgebildete Redakteurin ist Heide eher zuf\u00e4llig in der Baubranche gelandet. Seit 2011 arbeitet sie f\u00fcr pro clima. Ihr Wissen zu effektiver Kommunikation gibt sie in Seminaren, Artikeln und Vortr\u00e4gen weiter. F\u00fcr den pro clima Blog, proclima.tv und das pro clima Bauradio interviewt sie interessante Menschen aus der Baubranche. Auf\u00a0 luftdichtheit-gepr\u00fcft.de bloggt Heide \u00fcber Leckagen, Luftdichtung und Qualit\u00e4ts\u00fcberpr\u00fcfung mit Blower-Door-Tests. Ihre Freizeit verbringt sie u.a. in den Vogesen, wo sie seit mehr als f\u00fcnf Jahren ein altes Bauernhaus saniert. Ihr neuestes Projekt:\u00a0 www.besser-als-marketing.de Hier gibt es Tipps, wie Unternehmen in der Baubranche ihre Sichtbarkeit erh\u00f6hen k\u00f6nnen. Die ersten Videos sind bereits online im Youtube Channel Wer mehr \u00fcber Heide Merkel erfahren m\u00f6chte, findet sie auf den g\u00e4ngigen Social Media Plattformen.\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/author\\\/gentner\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BUILDAIR 2013 - Eindr\u00fccke der pro clima Regionalvertretung Nord  - pro clima Blog - Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.proclima.com\/de\/buildair\/","og_locale":"de_DE","og_type":"article","og_title":"BUILDAIR 2013 - Eindr\u00fccke der pro clima Regionalvertretung Nord  - pro clima Blog - Deutschland","og_description":"Neben dem pro clima Gr\u00fcnder Lothar Moll und Ingenieur Stefan H\u00fcckst\u00e4dt, ist auch die pro clima Regionalvertretung Nord auf der BUILDAIR 2013 in Hannover gewesen. ...","og_url":"https:\/\/blog.proclima.com\/de\/buildair\/","og_site_name":"pro clima Blog - Deutschland","article_published_time":"2013-06-10T08:47:48+00:00","article_modified_time":"2013-06-11T09:32:11+00:00","og_image":[{"url":"https:\/\/blog.proclima.com\/de\/files\/2013\/06\/IMG_1457-1024x682.jpg","type":"","width":"","height":""}],"author":"Heide Merkel","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Heide Merkel","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.proclima.com\/de\/buildair\/#article","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/buildair\/"},"author":{"name":"Heide Merkel","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/d82bffdd044ae90e51f35347afa56918"},"headline":"BUILDAIR 2013 &#8211; Eindr\u00fccke der pro clima Regionalvertretung Nord","datePublished":"2013-06-10T08:47:48+00:00","dateModified":"2013-06-11T09:32:11+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.proclima.com\/de\/buildair\/"},"wordCount":244,"commentCount":0,"image":{"@id":"https:\/\/blog.proclima.com\/de\/buildair\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.proclima.com\/de\/files\/2013\/06\/IMG_1457-1024x682.jpg","keywords":["Detlef Gro\u00df","Joachim Gro\u00df","Lothar Moll","pro clima Gr\u00fcnder","Stefan H\u00fcckst\u00e4dt"],"articleSection":["pro clima"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.proclima.com\/de\/buildair\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.proclima.com\/de\/buildair\/","url":"https:\/\/blog.proclima.com\/de\/buildair\/","name":"BUILDAIR 2013 - Eindr\u00fccke der pro clima Regionalvertretung Nord - pro clima Blog - Deutschland","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.proclima.com\/de\/buildair\/#primaryimage"},"image":{"@id":"https:\/\/blog.proclima.com\/de\/buildair\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.proclima.com\/de\/files\/2013\/06\/IMG_1457-1024x682.jpg","datePublished":"2013-06-10T08:47:48+00:00","dateModified":"2013-06-11T09:32:11+00:00","author":{"@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/d82bffdd044ae90e51f35347afa56918"},"breadcrumb":{"@id":"https:\/\/blog.proclima.com\/de\/buildair\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.proclima.com\/de\/buildair\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.proclima.com\/de\/buildair\/#primaryimage","url":"https:\/\/blog.proclima.com\/de\/files\/2013\/06\/IMG_1457-scaled.jpg","contentUrl":"https:\/\/blog.proclima.com\/de\/files\/2013\/06\/IMG_1457-scaled.jpg","width":2560,"height":1707,"caption":"Von links: pro clima Gr\u00fcnder Lothar Moll, Ruwen, Detlef und Joachim Gro\u00df von gross-baupraxis.de (pro clima Regionalvertretung Nord), Energieberater Frank Brockmann und pro clima Techniker Stefan H\u00fcckst\u00e4dt"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.proclima.com\/de\/buildair\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/blog.proclima.com\/de\/"},{"@type":"ListItem","position":2,"name":"BUILDAIR 2013 &#8211; Eindr\u00fccke der pro clima Regionalvertretung Nord"}]},{"@type":"WebSite","@id":"https:\/\/blog.proclima.com\/de\/#website","url":"https:\/\/blog.proclima.com\/de\/","name":"pro clima Blog - Deutschland","description":"alles was pro clima bewegt","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.proclima.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/d82bffdd044ae90e51f35347afa56918","name":"Heide Merkel","description":"Fachjournalistin, Referentin, Steuerung Presse &amp; Digitale Medien bei Moll bau\u00f6kologische Produkte GmbH (pro clima). Als Japanologin und ausgebildete Redakteurin ist Heide eher zuf\u00e4llig in der Baubranche gelandet. Seit 2011 arbeitet sie f\u00fcr pro clima. Ihr Wissen zu effektiver Kommunikation gibt sie in Seminaren, Artikeln und Vortr\u00e4gen weiter. F\u00fcr den pro clima Blog, proclima.tv und das pro clima Bauradio interviewt sie interessante Menschen aus der Baubranche. Auf\u00a0 luftdichtheit-gepr\u00fcft.de bloggt Heide \u00fcber Leckagen, Luftdichtung und Qualit\u00e4ts\u00fcberpr\u00fcfung mit Blower-Door-Tests. Ihre Freizeit verbringt sie u.a. in den Vogesen, wo sie seit mehr als f\u00fcnf Jahren ein altes Bauernhaus saniert. Ihr neuestes Projekt:\u00a0 www.besser-als-marketing.de Hier gibt es Tipps, wie Unternehmen in der Baubranche ihre Sichtbarkeit erh\u00f6hen k\u00f6nnen. Die ersten Videos sind bereits online im Youtube Channel Wer mehr \u00fcber Heide Merkel erfahren m\u00f6chte, findet sie auf den g\u00e4ngigen Social Media Plattformen.","url":"https:\/\/blog.proclima.com\/de\/author\/gentner\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/3062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/comments?post=3062"}],"version-history":[{"count":8,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/3062\/revisions"}],"predecessor-version":[{"id":3070,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/3062\/revisions\/3070"}],"wp:attachment":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/media?parent=3062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/categories?post=3062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/tags?post=3062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}