{"id":10970,"date":"2024-05-15T17:18:01","date_gmt":"2024-05-15T15:18:01","guid":{"rendered":"https:\/\/blog.proclima.com\/de\/?p=10970"},"modified":"2024-05-15T17:49:39","modified_gmt":"2024-05-15T15:49:39","slug":"ueberfragt-zu-den-neuerungen-des-zvdh","status":"publish","type":"post","link":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/","title":{"rendered":"\u00dcberfragt zu den Neuerungen des ZVDH?"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Wir bringen es auf den Punkt! <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Im April 2024 ver\u00f6ffentlichte der Zentralverband des deutschen Dachdeckerhandwerks (kurz ZVDH) Neuerungen seines Fachregelwerks in Form einer Erg\u00e4nzungslieferung \u2013 Anlass f\u00fcr uns, hier einmal genauer hinzusehen und etwas Licht ins Dunkle zu bringen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im pro clima Online-Seminar \u201e<em>\u00dcberfragt zu den Neuerungen des ZVDH Regelwerks? &#8211; Wir bringen es auf den Punkt!<\/em>\u201c vom 10. April 2024 haben wir die wesentlichen \u00c4nderungen, und was diese f\u00fcr Sie im Handwerk konkret bedeuten, kompakt aufbereitet. F\u00fcr alle Interessierten gibt es die Aufzeichnung des Livestreams hier zum Nachschauen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">pro clima Livestream: \u00c4nderung des ZVDH Regelwerks<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\"  id=\"_ytid_36326\"  width=\"1170\" height=\"658\"  data-origwidth=\"1170\" data-origheight=\"658\" src=\"https:\/\/www.youtube.com\/embed\/nEGcLxsuuoM?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=1&#038;playsinline=1&#038;autohide=2&#038;theme=light&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\"><br>+ Neues Produktdatenblatt Unterdeck- und Unterspannbahnen (UDB \/ USB)<br>+ Neues Merkblatt f\u00fcr Unterd\u00e4cher, Unterdeckungen und Unterspannungen<br>+ Neue Fachregel f\u00fcr Dachdeckungen mit Dachziegeln und Dachsteinen<br>+ Neues Merkblatt W\u00e4rmeschutz bei Dach und Wand<br>+ weitere \u00c4nderungen der Fachregel als \u00dcbersicht.<\/figcaption><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Das ZVDH-Regelwerk des Deutschen Dachdeckerhandwerks beinhaltet alle Anforderungen, Vorschriften und Regeln, die Sie f\u00fcr eine fachgerechte und sichere Ausf\u00fchrung von Dach-, Wand- und Abdichtungsarbeiten ben\u00f6tigen. Das Deutsche Dachdeckerhandwerk Regelwerk wird vom Zentralverband des Deutschen Dachdeckerhandwerks &#8211; Fachverband f\u00fcr Dach-,Wandund Abdichtungstechnik &#8211; e. V. Regelm\u00e4\u00dfig dem neuesten Stand der Technik angepasst.<br>(Quelle: https:\/\/www.ddh.de\/)<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erfahre alles \u00fcber die wesentlichen \u00c4nderungen des ZVDH Regelwerks und was dies f\u00fcr Dich im Dachdeckerhandwerk bedeutet. <\/p>\n","protected":false},"author":42,"featured_media":10976,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,6],"tags":[6240,1507,6239,6238,1401,6175,6176,1290],"class_list":["post-10970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proclima","category-schulungen","tag-dachdeckerhandwerk","tag-dacheindeckung","tag-ergaenzungslieferung","tag-regelwerk","tag-unterdach","tag-unterdeckbahn","tag-unterspannbahn","tag-zvdh"],"canto_acf_fields":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcberfragt zu den Neuerungen des ZVDH? - pro clima Blog - Deutschland<\/title>\n<meta name=\"description\" content=\"Alles \u00fcber die wesentlichen \u00c4nderungen des ZVDH Regelwerks zum April 2024 und was diese konkret f\u00fcr das Handwerk bedeuten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcberfragt zu den Neuerungen des ZVDH? - pro clima Blog - Deutschland\" \/>\n<meta property=\"og:description\" content=\"Alles \u00fcber die wesentlichen \u00c4nderungen des ZVDH Regelwerks zum April 2024 und was diese konkret f\u00fcr das Handwerk bedeuten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/\" \/>\n<meta property=\"og:site_name\" content=\"pro clima Blog - Deutschland\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-15T15:18:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-15T15:49:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.proclima.com\/de\/files\/2024\/05\/Teaserbild_Streaming_Veroeffentlichung_ZVDH_Neuerung_Regelwerk_2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1616\" \/>\n\t<meta property=\"og:image:height\" content=\"906\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"favaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"favaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/ueberfragt-zu-den-neuerungen-des-zvdh\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/ueberfragt-zu-den-neuerungen-des-zvdh\\\/\"},\"author\":{\"name\":\"favaro\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/05f6ff0a8811b5080f860e8b3a192521\"},\"headline\":\"\u00dcberfragt zu den Neuerungen des ZVDH?\",\"datePublished\":\"2024-05-15T15:18:01+00:00\",\"dateModified\":\"2024-05-15T15:49:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/ueberfragt-zu-den-neuerungen-des-zvdh\\\/\"},\"wordCount\":210,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/ueberfragt-zu-den-neuerungen-des-zvdh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2024\\\/05\\\/Teaserbild_Streaming_Veroeffentlichung_ZVDH_Neuerung_Regelwerk_2024.jpg\",\"keywords\":[\"dachdeckerhandwerk\",\"Dacheindeckung\",\"erg\u00e4nzungslieferung\",\"regelwerk\",\"Unterdach\",\"Unterdeckbahn\",\"Unterspannbahn\",\"ZVDH\"],\"articleSection\":[\"pro clima\",\"Schulungen\\\/Seminare\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/ueberfragt-zu-den-neuerungen-des-zvdh\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/ueberfragt-zu-den-neuerungen-des-zvdh\\\/\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/ueberfragt-zu-den-neuerungen-des-zvdh\\\/\",\"name\":\"\u00dcberfragt zu den Neuerungen des ZVDH? - pro clima Blog - Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/ueberfragt-zu-den-neuerungen-des-zvdh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/ueberfragt-zu-den-neuerungen-des-zvdh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2024\\\/05\\\/Teaserbild_Streaming_Veroeffentlichung_ZVDH_Neuerung_Regelwerk_2024.jpg\",\"datePublished\":\"2024-05-15T15:18:01+00:00\",\"dateModified\":\"2024-05-15T15:49:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/05f6ff0a8811b5080f860e8b3a192521\"},\"description\":\"Alles \u00fcber die wesentlichen \u00c4nderungen des ZVDH Regelwerks zum April 2024 und was diese konkret f\u00fcr das Handwerk bedeuten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/ueberfragt-zu-den-neuerungen-des-zvdh\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/ueberfragt-zu-den-neuerungen-des-zvdh\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/ueberfragt-zu-den-neuerungen-des-zvdh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2024\\\/05\\\/Teaserbild_Streaming_Veroeffentlichung_ZVDH_Neuerung_Regelwerk_2024.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2024\\\/05\\\/Teaserbild_Streaming_Veroeffentlichung_ZVDH_Neuerung_Regelwerk_2024.jpg\",\"width\":1616,\"height\":906},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/ueberfragt-zu-den-neuerungen-des-zvdh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcberfragt zu den Neuerungen des ZVDH?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\",\"name\":\"pro clima Blog - Deutschland\",\"description\":\"alles was pro clima bewegt\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/05f6ff0a8811b5080f860e8b3a192521\",\"name\":\"favaro\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/author\\\/favaro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcberfragt zu den Neuerungen des ZVDH? - pro clima Blog - Deutschland","description":"Alles \u00fcber die wesentlichen \u00c4nderungen des ZVDH Regelwerks zum April 2024 und was diese konkret f\u00fcr das Handwerk bedeuten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/","og_locale":"de_DE","og_type":"article","og_title":"\u00dcberfragt zu den Neuerungen des ZVDH? - pro clima Blog - Deutschland","og_description":"Alles \u00fcber die wesentlichen \u00c4nderungen des ZVDH Regelwerks zum April 2024 und was diese konkret f\u00fcr das Handwerk bedeuten.","og_url":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/","og_site_name":"pro clima Blog - Deutschland","article_published_time":"2024-05-15T15:18:01+00:00","article_modified_time":"2024-05-15T15:49:39+00:00","og_image":[{"width":1616,"height":906,"url":"https:\/\/blog.proclima.com\/de\/files\/2024\/05\/Teaserbild_Streaming_Veroeffentlichung_ZVDH_Neuerung_Regelwerk_2024.jpg","type":"image\/jpeg"}],"author":"favaro","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"favaro","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/#article","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/"},"author":{"name":"favaro","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/05f6ff0a8811b5080f860e8b3a192521"},"headline":"\u00dcberfragt zu den Neuerungen des ZVDH?","datePublished":"2024-05-15T15:18:01+00:00","dateModified":"2024-05-15T15:49:39+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/"},"wordCount":210,"commentCount":0,"image":{"@id":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.proclima.com\/de\/files\/2024\/05\/Teaserbild_Streaming_Veroeffentlichung_ZVDH_Neuerung_Regelwerk_2024.jpg","keywords":["dachdeckerhandwerk","Dacheindeckung","erg\u00e4nzungslieferung","regelwerk","Unterdach","Unterdeckbahn","Unterspannbahn","ZVDH"],"articleSection":["pro clima","Schulungen\/Seminare"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/","url":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/","name":"\u00dcberfragt zu den Neuerungen des ZVDH? - pro clima Blog - Deutschland","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/#primaryimage"},"image":{"@id":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.proclima.com\/de\/files\/2024\/05\/Teaserbild_Streaming_Veroeffentlichung_ZVDH_Neuerung_Regelwerk_2024.jpg","datePublished":"2024-05-15T15:18:01+00:00","dateModified":"2024-05-15T15:49:39+00:00","author":{"@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/05f6ff0a8811b5080f860e8b3a192521"},"description":"Alles \u00fcber die wesentlichen \u00c4nderungen des ZVDH Regelwerks zum April 2024 und was diese konkret f\u00fcr das Handwerk bedeuten.","breadcrumb":{"@id":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/#primaryimage","url":"https:\/\/blog.proclima.com\/de\/files\/2024\/05\/Teaserbild_Streaming_Veroeffentlichung_ZVDH_Neuerung_Regelwerk_2024.jpg","contentUrl":"https:\/\/blog.proclima.com\/de\/files\/2024\/05\/Teaserbild_Streaming_Veroeffentlichung_ZVDH_Neuerung_Regelwerk_2024.jpg","width":1616,"height":906},{"@type":"BreadcrumbList","@id":"https:\/\/blog.proclima.com\/de\/ueberfragt-zu-den-neuerungen-des-zvdh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/blog.proclima.com\/de\/"},{"@type":"ListItem","position":2,"name":"\u00dcberfragt zu den Neuerungen des ZVDH?"}]},{"@type":"WebSite","@id":"https:\/\/blog.proclima.com\/de\/#website","url":"https:\/\/blog.proclima.com\/de\/","name":"pro clima Blog - Deutschland","description":"alles was pro clima bewegt","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.proclima.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/05f6ff0a8811b5080f860e8b3a192521","name":"favaro","url":"https:\/\/blog.proclima.com\/de\/author\/favaro\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/10970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/comments?post=10970"}],"version-history":[{"count":7,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/10970\/revisions"}],"predecessor-version":[{"id":10978,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/10970\/revisions\/10978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/media\/10976"}],"wp:attachment":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/media?parent=10970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/categories?post=10970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/tags?post=10970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}