
{"id":10206,"date":"2022-10-18T09:00:00","date_gmt":"2022-10-18T07:00:00","guid":{"rendered":"https:\/\/blog.proclima.com\/de\/?p=10206"},"modified":"2022-08-22T14:10:21","modified_gmt":"2022-08-22T12:10:21","slug":"gemeinschaftlich-moeglichkeiten-wachsen-lassen","status":"publish","type":"post","link":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/","title":{"rendered":"Gemeinschaftlich M\u00f6glichkeiten wachsen lassen"},"content":{"rendered":"\n<p>Am 23. Juni 2022 feierte pro clima Sommerfest. Man kam zusammen, war unbeschwert, die Stimmung war voller positiver Lebensfreude \u2013 es wurde getanzt und die Gemeinschaft gefeiert.<\/p>\n\n\n\n<p>Erfahren Sie hier mehr zur Stimmung dem Gemeinschaftsgef\u00fchl beim pro clima Sommerfest.<\/p>\n\n\n\n<p><a href=\"https:\/\/de.proclima.com\/aktion\/lust-auf\/lust-auf-gemeinschaft\" target=\"_blank\" rel=\"noreferrer noopener\">Lust auf GEMEINSCHAFT<\/a><\/p>\n\n\n\n<p>In unserer \u201eLust auf\u2026\u201c Reihe stellen wir verschiedene Projekte und Themen vor.<\/p>\n\n\n\n<p>Gemeinschaftlich &#8211; in Kooperationen und mit Partnern &#8211; lassen wir unsere M\u00f6glichkeiten wachsen. Der Mensch steht bei pro clima im Mittelpunkt allen Handelns. Insgesamt spielt hier das menschliche Miteinander, der Spa\u00df am Handeln und die Gemeinschaft eine gro\u00dfe Rolle. Denn: Der Mensch ist der Schl\u00fcssel f\u00fcr Entwicklung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 23. Juni 2022 feierte pro clima Sommerfest. Man kam zusammen, war unbeschwert, die Stimmung war voller positiver Lebensfreude \u2013 es wurde getanzt und die <a href=\"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/\" rel=\"bookmark\">&#8230;<\/a><\/p>\n","protected":false},"author":453,"featured_media":10209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proclima"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gemeinschaftlich M\u00f6glichkeiten wachsen lassen &#187; pro clima Blog - Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gemeinschaftlich M\u00f6glichkeiten wachsen lassen &#187; pro clima Blog - Deutschland\" \/>\n<meta property=\"og:description\" content=\"Am 23. Juni 2022 feierte pro clima Sommerfest. Man kam zusammen, war unbeschwert, die Stimmung war voller positiver Lebensfreude \u2013 es wurde getanzt und die ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/\" \/>\n<meta property=\"og:site_name\" content=\"pro clima Blog - Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proclima\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-18T07:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/GEMEINSCHAFT-Beitragsbild.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1219\" \/>\n\t<meta property=\"og:image:height\" content=\"677\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Friederike Remiorz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@proclimaDE\" \/>\n<meta name=\"twitter:site\" content=\"@proclimaDE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Friederike Remiorz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/10\\\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/10\\\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\\\/\"},\"author\":{\"name\":\"Friederike Remiorz\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/c596ad1307bfc3dc78019a7338a86dc1\"},\"headline\":\"Gemeinschaftlich M\u00f6glichkeiten wachsen lassen\",\"datePublished\":\"2022-10-18T07:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/10\\\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\\\/\"},\"wordCount\":108,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/10\\\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2022\\\/08\\\/GEMEINSCHAFT-Beitragsbild.jpg\",\"articleSection\":[\"pro clima\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/10\\\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/10\\\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\\\/\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/10\\\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\\\/\",\"name\":\"Gemeinschaftlich M\u00f6glichkeiten wachsen lassen &#187; pro clima Blog - Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/10\\\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/10\\\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2022\\\/08\\\/GEMEINSCHAFT-Beitragsbild.jpg\",\"datePublished\":\"2022-10-18T07:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/10\\\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/10\\\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/10\\\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2022\\\/08\\\/GEMEINSCHAFT-Beitragsbild.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2022\\\/08\\\/GEMEINSCHAFT-Beitragsbild.jpg\",\"width\":1219,\"height\":677},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/10\\\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gemeinschaftlich M\u00f6glichkeiten wachsen lassen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\",\"name\":\"pro clima Blog - Deutschland\",\"description\":\"alles was pro clima bewegt\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#organization\",\"name\":\"pro clima - Moll bau\u00f6kologische Produkte GmbH\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2020\\\/04\\\/Logo-pro-clima.png\",\"contentUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2020\\\/04\\\/Logo-pro-clima.png\",\"width\":4210,\"height\":4881,\"caption\":\"pro clima - Moll bau\u00f6kologische Produkte GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/proclima\",\"https:\\\/\\\/x.com\\\/proclimaDE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/c596ad1307bfc3dc78019a7338a86dc1\",\"name\":\"Friederike Remiorz\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/author\\\/remiorz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gemeinschaftlich M\u00f6glichkeiten wachsen lassen &#187; pro clima Blog - Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/","og_locale":"de_DE","og_type":"article","og_title":"Gemeinschaftlich M\u00f6glichkeiten wachsen lassen &#187; pro clima Blog - Deutschland","og_description":"Am 23. Juni 2022 feierte pro clima Sommerfest. Man kam zusammen, war unbeschwert, die Stimmung war voller positiver Lebensfreude \u2013 es wurde getanzt und die ...","og_url":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/","og_site_name":"pro clima Blog - Deutschland","article_publisher":"https:\/\/www.facebook.com\/proclima","article_published_time":"2022-10-18T07:00:00+00:00","og_image":[{"width":1219,"height":677,"url":"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/GEMEINSCHAFT-Beitragsbild.jpg","type":"image\/jpeg"}],"author":"Friederike Remiorz","twitter_card":"summary_large_image","twitter_creator":"@proclimaDE","twitter_site":"@proclimaDE","twitter_misc":{"Verfasst von":"Friederike Remiorz","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/#article","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/"},"author":{"name":"Friederike Remiorz","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/c596ad1307bfc3dc78019a7338a86dc1"},"headline":"Gemeinschaftlich M\u00f6glichkeiten wachsen lassen","datePublished":"2022-10-18T07:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/"},"wordCount":108,"commentCount":0,"publisher":{"@id":"https:\/\/blog.proclima.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/GEMEINSCHAFT-Beitragsbild.jpg","articleSection":["pro clima"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/","url":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/","name":"Gemeinschaftlich M\u00f6glichkeiten wachsen lassen &#187; pro clima Blog - Deutschland","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/#primaryimage"},"image":{"@id":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/GEMEINSCHAFT-Beitragsbild.jpg","datePublished":"2022-10-18T07:00:00+00:00","breadcrumb":{"@id":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/#primaryimage","url":"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/GEMEINSCHAFT-Beitragsbild.jpg","contentUrl":"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/GEMEINSCHAFT-Beitragsbild.jpg","width":1219,"height":677},{"@type":"BreadcrumbList","@id":"https:\/\/blog.proclima.com\/de\/2022\/10\/gemeinschaftlich-moeglichkeiten-wachsen-lassen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.proclima.com\/de\/"},{"@type":"ListItem","position":2,"name":"Gemeinschaftlich M\u00f6glichkeiten wachsen lassen"}]},{"@type":"WebSite","@id":"https:\/\/blog.proclima.com\/de\/#website","url":"https:\/\/blog.proclima.com\/de\/","name":"pro clima Blog - Deutschland","description":"alles was pro clima bewegt","publisher":{"@id":"https:\/\/blog.proclima.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.proclima.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.proclima.com\/de\/#organization","name":"pro clima - Moll bau\u00f6kologische Produkte GmbH","url":"https:\/\/blog.proclima.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.proclima.com\/de\/files\/2020\/04\/Logo-pro-clima.png","contentUrl":"https:\/\/blog.proclima.com\/de\/files\/2020\/04\/Logo-pro-clima.png","width":4210,"height":4881,"caption":"pro clima - Moll bau\u00f6kologische Produkte GmbH"},"image":{"@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/proclima","https:\/\/x.com\/proclimaDE"]},{"@type":"Person","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/c596ad1307bfc3dc78019a7338a86dc1","name":"Friederike Remiorz","url":"https:\/\/blog.proclima.com\/de\/author\/remiorz\/"}]}},"canto_acf_fields":"","_links":{"self":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/10206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/users\/453"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/comments?post=10206"}],"version-history":[{"count":1,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/10206\/revisions"}],"predecessor-version":[{"id":10207,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/10206\/revisions\/10207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/media\/10209"}],"wp:attachment":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/media?parent=10206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/categories?post=10206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/tags?post=10206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}