
{"id":10164,"date":"2022-08-07T14:58:19","date_gmt":"2022-08-07T12:58:19","guid":{"rendered":"https:\/\/blog.proclima.com\/de\/?p=10164"},"modified":"2022-08-07T14:58:21","modified_gmt":"2022-08-07T12:58:21","slug":"einzigartig-nervenaufreibend-lehrreich","status":"publish","type":"post","link":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/","title":{"rendered":"Einzigartig, nervenaufreibend, lehrreich"},"content":{"rendered":"\n<p>2,5 Jahre Planung und Konstruktion, wochenlanger Aufbau der Demonstrations-Unit \u2013 all die Vorbereitungen der teilnehmenden Teams gipfelten im 10-t\u00e4gigen Hochschulwettbewerb vor Ort in Wuppertal. Die drei von pro clima unterst\u00fctzten Teams erbrachten tolle Leistungen und kletterten mit Team AuRA (FR) sogar auf das Siegertreppchen, Platz 3. Das Team X4S aus Biberach belegte einen tollen Platz 11 und Team FIRSTLIFE aus Tschechien schaffte es direkt dahinter auf den 12. Platz. Alle Ergebnisse des Wettbewerbs sind hier zu finden: <a href=\"https:\/\/sde21.eu\/de\/results\">https:\/\/sde21.eu\/de\/results<\/a>. Vergangene Woche, ca. 1 1\/2 Monate nach dem Solar Decathlon Europe 21\/22, blickt das Team X4S auf die Teilnahme am SDE 21\/22 zur\u00fcck. Professor Andreas Gerber und Projektleiterin Lena Fr\u00fchsch\u00fctz berichten im kleinsten Kreise von den Erfahrungen und Erlebnissen im Rahmen der Teilnahme.<\/p>\n\n\n\n<p><strong>Vorbilder der Baukultur<\/strong><\/p>\n\n\n\n<p>\u201eEs war eine ganz wertvolle, lehrreiche und tolle Zeit, aber auch nervenaufreibend und mit Stress verbunden\u201c, res\u00fcmiert Lena Fr\u00fchsch\u00fctz. Das sind nur ein paar der Adjektive, die die Reise der Biberacher hin zum Solar Decathlon Europe 21\/22 in Wuppertal beschreiben. Das eher kleine Team verwirklichte dabei mit Bravour sein gro\u00dfes Ziel: das Thema Nachhaltigkeit von Beginn an und ganzheitlich im Projekt mitzudenken und umzusetzen. Das Ergebnis kann sich sehen lassen: Ein rundum nachhaltiges Geb\u00e4ude mit vielen innovativen Ans\u00e4tzen. Damit \u00fcbernimmt das Team ebenso wie die anderen 17 Mitstreiter eine Vorbildfunktion f\u00fcr die k\u00fcnftige Baukultur.<\/p>\n\n\n\n<p>\u201e<strong>Wir haben ein Geb\u00e4ude geschaffen\u201c<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Vor Ort hatte das Team X4S zun\u00e4chst unvorhergesehene H\u00fcrden zu meistern: Zun\u00e4chst kein Kran, LKW-Anlieferungen in falscher Reihenfolge oder nur vor den Toren des Gel\u00e4ndes, Zeitverz\u00f6gerungen und dann auch noch Sturzregen. Da das Team in der Vorfertigung nicht so weit gekommen war, wie gew\u00fcnscht, waren die Schichtpl\u00e4ne ab Tag 2 zu Makulatur erkl\u00e4rt \u2013 alle gaben rund um die Uhr alles. Und als endlich die erste Decke eingezogen war, war er da: der erste gro\u00dfe G\u00e4nsehautmoment \u2013 \u201eWir haben ein Geb\u00e4ude geschaffen\u201c, schw\u00e4rmt Lena Fr\u00fchsch\u00fctz.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF2558-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF2558-683x1024.jpg\" alt=\"\" class=\"wp-image-10169\" srcset=\"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF2558-683x1024.jpg 683w, https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF2558-200x300.jpg 200w, https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF2558-768x1152.jpg 768w, https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF2558-1024x1536.jpg 1024w, https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF2558-1365x2048.jpg 1365w, https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF2558-256x384.jpg 256w, https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF2558-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/a><figcaption>\u00a9 Team X4S \/ SDE 21\u00bb22<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\"  id=\"_ytid_62349\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/sgBXX5-YCDc?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;iv_load_policy=1&#038;loop=0&#038;modestbranding=1&#038;rel=0&#038;showinfo=0&#038;fs=1&#038;playsinline=1&#038;controls=2&#038;autohide=2&#038;theme=light&#038;color=red&#038;hl=de_DE&#038;\" class=\"__youtube_prefs__\" title=\"YouTube player\"  allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe>\n<\/div><figcaption>Eindruck vom Baustellenleben vor Ort &#8211; Quelle: Solar Decathlon Europe 21-22<\/figcaption><\/figure>\n\n\n\n<p><strong>Tolle Behaglichkeitswerte und einzigartige Luftdichtung durch INTELLO<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Besonders gelobt wurde das Solardach, das nicht aus herk\u00f6mmlichen Paneelen sondern aus R\u00f6hren besteht und somit licht- und wasserdurchl\u00e4ssig ist: So wird auf dem Dachgarten ein angenehmes halb-schattiges Klima erreicht, welches sich auch f\u00fcr die angebauten Nutz- und Zierpflanzen als optimal herausstellte. Im Gegensatz zu den meisten Teams, schafften es die Biberacher in ihrem Modell eine luftdichte Geb\u00e4udeh\u00fclle herzustellen. Hierf\u00fcr wurde die pro clima INTELLO verwendet. Auch besonders hervorzuheben sind die dadurch sehr guten Behaglichkeitswerte in der Demonstrations-Unit sowie die angenehmen Innentemperaturen auch an hei\u00dfen Sommertagen.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF25851-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF25851-683x1024.jpg\" alt=\"\" class=\"wp-image-10168\" srcset=\"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF25851-683x1024.jpg 683w, https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF25851-200x300.jpg 200w, https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF25851-768x1152.jpg 768w, https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF25851-1024x1536.jpg 1024w, https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF25851-1365x2048.jpg 1365w, https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF25851-256x384.jpg 256w, https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF25851-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/a><figcaption>\u00a9 Team X4S \/ SDE 21\u00bb22<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p><strong>Wie geht es weiter?<\/strong><\/p>\n\n\n\n<p>Nachdem der SDE am 26. Juni 22 zu Ende ging, bleiben acht der H\u00e4user f\u00fcr mindestens drei Jahre auf dem Gel\u00e4nde stehen \u2013 auch das der Biberacher. Sie dienen hier weiterhin als Forschungsobjekte f\u00fcr Universit\u00e4tsangeh\u00f6rige, die sich mit dem nachhaltigen Bauen auseinander setzen. In regelm\u00e4\u00dfigen F\u00fchrungen werden die Units auch der \u00d6ffentlichkeit zug\u00e4nglich gemacht. Des Weiteren besteht die M\u00f6glichkeit den Campus digital zu besuchen: <a href=\"https:\/\/sde21.eu\/de\/digital-campus\">https:\/\/sde21.eu\/de\/digital-campus<\/a>. F\u00fcr pro clima war die Unterst\u00fctzung der Teams beim SDE 21\/22, deren Reise zu begleiten und Teil der innovativen und zukunftsweisenden Projekte zu sein eine pure Freude.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2,5 Jahre Planung und Konstruktion, wochenlanger Aufbau der Demonstrations-Unit \u2013 all die Vorbereitungen der teilnehmenden Teams gipfelten im 10-t\u00e4gigen Hochschulwettbewerb vor Ort in Wuppertal. Die <a href=\"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/\" rel=\"bookmark\">&#8230;<\/a><\/p>\n","protected":false},"author":453,"featured_media":10167,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proclima"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Einzigartig, nervenaufreibend, lehrreich &#187; pro clima Blog - Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Einzigartig, nervenaufreibend, lehrreich &#187; pro clima Blog - Deutschland\" \/>\n<meta property=\"og:description\" content=\"2,5 Jahre Planung und Konstruktion, wochenlanger Aufbau der Demonstrations-Unit \u2013 all die Vorbereitungen der teilnehmenden Teams gipfelten im 10-t\u00e4gigen Hochschulwettbewerb vor Ort in Wuppertal. Die ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/\" \/>\n<meta property=\"og:site_name\" content=\"pro clima Blog - Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proclima\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-07T12:58:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-07T12:58:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF3074-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Friederike Remiorz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@proclimaDE\" \/>\n<meta name=\"twitter:site\" content=\"@proclimaDE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Friederike Remiorz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/08\\\/einzigartig-nervenaufreibend-lehrreich\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/08\\\/einzigartig-nervenaufreibend-lehrreich\\\/\"},\"author\":{\"name\":\"Friederike Remiorz\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/c596ad1307bfc3dc78019a7338a86dc1\"},\"headline\":\"Einzigartig, nervenaufreibend, lehrreich\",\"datePublished\":\"2022-08-07T12:58:19+00:00\",\"dateModified\":\"2022-08-07T12:58:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/08\\\/einzigartig-nervenaufreibend-lehrreich\\\/\"},\"wordCount\":568,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/08\\\/einzigartig-nervenaufreibend-lehrreich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2022\\\/08\\\/DSCF3074-scaled.jpg\",\"articleSection\":[\"pro clima\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/08\\\/einzigartig-nervenaufreibend-lehrreich\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/08\\\/einzigartig-nervenaufreibend-lehrreich\\\/\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/08\\\/einzigartig-nervenaufreibend-lehrreich\\\/\",\"name\":\"Einzigartig, nervenaufreibend, lehrreich &#187; pro clima Blog - Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/08\\\/einzigartig-nervenaufreibend-lehrreich\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/08\\\/einzigartig-nervenaufreibend-lehrreich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2022\\\/08\\\/DSCF3074-scaled.jpg\",\"datePublished\":\"2022-08-07T12:58:19+00:00\",\"dateModified\":\"2022-08-07T12:58:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/08\\\/einzigartig-nervenaufreibend-lehrreich\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/08\\\/einzigartig-nervenaufreibend-lehrreich\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/08\\\/einzigartig-nervenaufreibend-lehrreich\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2022\\\/08\\\/DSCF3074-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2022\\\/08\\\/DSCF3074-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"\u00a9 Team X4S \\\/ SDE 21\u00bb22\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/2022\\\/08\\\/einzigartig-nervenaufreibend-lehrreich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einzigartig, nervenaufreibend, lehrreich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\",\"name\":\"pro clima Blog - Deutschland\",\"description\":\"alles was pro clima bewegt\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#organization\",\"name\":\"pro clima - Moll bau\u00f6kologische Produkte GmbH\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2020\\\/04\\\/Logo-pro-clima.png\",\"contentUrl\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/files\\\/2020\\\/04\\\/Logo-pro-clima.png\",\"width\":4210,\"height\":4881,\"caption\":\"pro clima - Moll bau\u00f6kologische Produkte GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/proclima\",\"https:\\\/\\\/x.com\\\/proclimaDE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/#\\\/schema\\\/person\\\/c596ad1307bfc3dc78019a7338a86dc1\",\"name\":\"Friederike Remiorz\",\"url\":\"https:\\\/\\\/blog.proclima.com\\\/de\\\/author\\\/remiorz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einzigartig, nervenaufreibend, lehrreich &#187; pro clima Blog - Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/","og_locale":"de_DE","og_type":"article","og_title":"Einzigartig, nervenaufreibend, lehrreich &#187; pro clima Blog - Deutschland","og_description":"2,5 Jahre Planung und Konstruktion, wochenlanger Aufbau der Demonstrations-Unit \u2013 all die Vorbereitungen der teilnehmenden Teams gipfelten im 10-t\u00e4gigen Hochschulwettbewerb vor Ort in Wuppertal. Die ...","og_url":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/","og_site_name":"pro clima Blog - Deutschland","article_publisher":"https:\/\/www.facebook.com\/proclima","article_published_time":"2022-08-07T12:58:19+00:00","article_modified_time":"2022-08-07T12:58:21+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF3074-scaled.jpg","type":"image\/jpeg"}],"author":"Friederike Remiorz","twitter_card":"summary_large_image","twitter_creator":"@proclimaDE","twitter_site":"@proclimaDE","twitter_misc":{"Verfasst von":"Friederike Remiorz","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/#article","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/"},"author":{"name":"Friederike Remiorz","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/c596ad1307bfc3dc78019a7338a86dc1"},"headline":"Einzigartig, nervenaufreibend, lehrreich","datePublished":"2022-08-07T12:58:19+00:00","dateModified":"2022-08-07T12:58:21+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/"},"wordCount":568,"commentCount":0,"publisher":{"@id":"https:\/\/blog.proclima.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF3074-scaled.jpg","articleSection":["pro clima"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/","url":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/","name":"Einzigartig, nervenaufreibend, lehrreich &#187; pro clima Blog - Deutschland","isPartOf":{"@id":"https:\/\/blog.proclima.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/#primaryimage"},"image":{"@id":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF3074-scaled.jpg","datePublished":"2022-08-07T12:58:19+00:00","dateModified":"2022-08-07T12:58:21+00:00","breadcrumb":{"@id":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/#primaryimage","url":"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF3074-scaled.jpg","contentUrl":"https:\/\/blog.proclima.com\/de\/files\/2022\/08\/DSCF3074-scaled.jpg","width":2560,"height":1707,"caption":"\u00a9 Team X4S \/ SDE 21\u00bb22"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.proclima.com\/de\/2022\/08\/einzigartig-nervenaufreibend-lehrreich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.proclima.com\/de\/"},{"@type":"ListItem","position":2,"name":"Einzigartig, nervenaufreibend, lehrreich"}]},{"@type":"WebSite","@id":"https:\/\/blog.proclima.com\/de\/#website","url":"https:\/\/blog.proclima.com\/de\/","name":"pro clima Blog - Deutschland","description":"alles was pro clima bewegt","publisher":{"@id":"https:\/\/blog.proclima.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.proclima.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.proclima.com\/de\/#organization","name":"pro clima - Moll bau\u00f6kologische Produkte GmbH","url":"https:\/\/blog.proclima.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.proclima.com\/de\/files\/2020\/04\/Logo-pro-clima.png","contentUrl":"https:\/\/blog.proclima.com\/de\/files\/2020\/04\/Logo-pro-clima.png","width":4210,"height":4881,"caption":"pro clima - Moll bau\u00f6kologische Produkte GmbH"},"image":{"@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/proclima","https:\/\/x.com\/proclimaDE"]},{"@type":"Person","@id":"https:\/\/blog.proclima.com\/de\/#\/schema\/person\/c596ad1307bfc3dc78019a7338a86dc1","name":"Friederike Remiorz","url":"https:\/\/blog.proclima.com\/de\/author\/remiorz\/"}]}},"canto_acf_fields":"","_links":{"self":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/10164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/users\/453"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/comments?post=10164"}],"version-history":[{"count":5,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/10164\/revisions"}],"predecessor-version":[{"id":10172,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/posts\/10164\/revisions\/10172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/media\/10167"}],"wp:attachment":[{"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/media?parent=10164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/categories?post=10164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.proclima.com\/de\/wp-json\/wp\/v2\/tags?post=10164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}